{"id":42933,"date":"2023-04-17T04:39:47","date_gmt":"2023-04-17T04:39:47","guid":{"rendered":"https:\/\/kodesolution.com\/2023\/amiso\/?page_id=42933"},"modified":"2023-08-21T16:15:14","modified_gmt":"2023-08-21T16:15:14","slug":"home-layout9","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/","title":{"rendered":"Home Layout9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"42933\" class=\"elementor elementor-42933\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9d04bf elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"a9d04bf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c7e529 tm-bg-color-over-image\" data-id=\"1c7e529\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f50f2e8 elementor-widget elementor-widget-tm-ele-text-editor-advanced\" data-id=\"f50f2e8\" data-element_type=\"widget\" data-widget_type=\"tm-ele-text-editor-advanced.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-text-editor-advanced\">\r\n\t\t\t\t\t<div class=\"each-item elementor-repeater-item-ecd7b45\">\r\n\t\t\t\t<h2>Web & App\nSolutions<\/h2>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"each-item elementor-repeater-item-6a63377\">\r\n\t\t\t\t<h5>Web Design & Development and App Making<\/h5>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e1040e elementor-widget elementor-widget-tm-ele-button\" data-id=\"9e1040e\" data-element_type=\"widget\" data-widget_type=\"tm-ele-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-button btn-view-details \">\r\n\t<a  href=\"#\" \r\n\t\t\t\t\t\tclass=\"btn btn-theme-colored1\">\r\n\r\n\t\t\r\n\t\t\r\n\t\t<span>\r\n\t\tContact Us\t\t<\/span>\r\n\r\n\t\t\t<\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d5ce877 tm-bg-color-over-image\" data-id=\"d5ce877\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5795743 elementor-hidden-mobile tm-bg-color-over-image\" data-id=\"5795743\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bb7097 elementor-widget elementor-widget-tm-ele-animated-layers\" data-id=\"3bb7097\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;}\" data-widget_type=\"tm-ele-animated-layers.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-sc-animated-layer-advanced \">\r\n\t\t\t<div class=\"animated-layer-advanced-inner clearfix\">\r\n\t\r\n<div class=\"layer-image-wrapper layer-image  layer-image-fullwidth elementor-repeater-item-a538756\" style=\"\">\r\n\t<div class=\"layer-inner layer-image  \">\r\n\t\t<div class=\"layer-image-inner-wrapper image-hover-effect-shine\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/art2.png\" width=\"709\" height=\"514\" alt=\"Image\">\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\r\n<div class=\"layer-image-wrapper layer-image  layer-image-fullwidth elementor-repeater-item-63197af\" style=\"\">\r\n\t<div class=\"layer-inner layer-image  \">\r\n\t\t<div class=\"layer-image-inner-wrapper image-hover-effect-shine\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/02\/Layer-4.png\" width=\"300\" height=\"308\" alt=\"Image\">\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\r\n<div class=\"layer-image-wrapper layer-image  layer-image-fullwidth elementor-repeater-item-96834a2\" style=\"\">\r\n\t<div class=\"layer-inner layer-image  tm-animation-spin\">\r\n\t\t<div class=\"layer-image-inner-wrapper \">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/02\/circle-text-dark.png\" width=\"233\" height=\"233\" alt=\"Image\">\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ef729e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"7ef729e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9940c42 tm-bg-color-over-image\" data-id=\"9940c42\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a90b289 elementor-widget elementor-widget-tm-ele-animated-layers\" data-id=\"a90b289\" data-element_type=\"widget\" data-widget_type=\"tm-ele-animated-layers.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-sc-animated-layer-advanced \">\r\n\t\t\t<div class=\"animated-layer-advanced-inner clearfix\">\r\n\t\r\n<div class=\"layer-image-wrapper layer-image  layer-image-fullwidth elementor-repeater-item-81cb61e\" style=\"\">\r\n\t<div class=\"layer-inner layer-image  \">\r\n\t\t<div class=\"layer-image-inner-wrapper image-hover-effect-shine\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/abt1-600x800.jpg\" width=\"600\" height=\"800\" alt=\"Image\">\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\r\n<div class=\"layer-image-wrapper layer-image  layer-image-fullwidth elementor-repeater-item-6b1b917\" style=\"\">\r\n\t<div class=\"layer-inner layer-image  \">\r\n\t\t<div class=\"layer-image-inner-wrapper image-hover-effect-shine\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/abt2.jpg\" width=\"2560\" height=\"1707\" alt=\"Image\">\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<div class=\"layer-image-wrapper  layer-blank  elementor-repeater-item-4c79047\" style=\"\">\r\n\t<div class=\"layer-inner\">\r\n\t<\/div>\r\n<\/div>\r\n\r\n<div class=\"layer-image-wrapper layer-image  layer-image-fullwidth elementor-repeater-item-76d1163\" style=\"\">\r\n\t<div class=\"layer-inner layer-image  tm-animation-floating\">\r\n\t\t<div class=\"layer-image-inner-wrapper \">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/dots.png\" width=\"75\" height=\"156\" alt=\"Image\">\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc07ad1 elementor-widget elementor-widget-tm-ele-floating-objects\" data-id=\"bc07ad1\" data-element_type=\"widget\" data-widget_type=\"tm-ele-floating-objects.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-ele-floating-objects \">\r\n\t<span class=\"each-object elementor-repeater-item-0a0d67a tm-animation-floating \" style=\"z-index: -1;\"><\/span>\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-438ddea tm-bg-color-over-image\" data-id=\"438ddea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-399be78 tm-bg-color-over-image\" data-id=\"399be78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aeb9cba horizontal-line-align-left vertical-line-align-bottom elementor-widget elementor-widget-tm-ele-section-title\" data-id=\"aeb9cba\" data-element_type=\"widget\" data-widget_type=\"tm-ele-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-section-title section-title \">\r\n\t<div class=\"title-wrapper\">\r\n\t\t\t\t\t\t<h6 class=\"subtitle \">\r\n\r\n\t\t\r\n\t\tABOUT\t<\/h6>\r\n\t\t\t\t<h2 class=\"title \">\r\n\r\n\t\t\r\n\t\t\t\t<span class=\"title-part1 \">The Affordable Designs<\/span>\r\n\t\t\t\t\r\n\t\t\r\n\t<\/h2>\r\n\t<div class=\"title-seperator-line\"><\/div>\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eda9d7 elementor-widget elementor-widget-tm-ele-text-editor\" data-id=\"2eda9d7\" data-element_type=\"widget\" data-widget_type=\"tm-ele-text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-text-editor\">\r\n\t\t<p>There are many variations of passages of available but the majority have suffered alteration in some form, by injected hum suffered alteration in some randomised words which don't slightly<\/p>\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85e7480 elementor-widget elementor-widget-tm-ele-list\" data-id=\"85e7480\" data-element_type=\"widget\" data-widget_type=\"tm-ele-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"tm-sc-list \">\r\n\t<li class=\"\">\r\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t<span>\r\n\tLorem Ipsum is not simply random text<\/span><\/li>\t<li class=\"\">\r\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t<span>\r\n\tLorem Ipsum is not simply random text<\/span><\/li><\/ul>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a3f7fc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"a3f7fc1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-22f3b40 tm-bg-color-over-image\" data-id=\"22f3b40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2732354 elementor-widget elementor-widget-tm-ele-iconbox\" data-id=\"2732354\" data-element_type=\"widget\" data-widget_type=\"tm-ele-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-icon-box icon-box icon-left tm-iconbox-icontype-no-icon icon-position-icon-left\" >\r\n\t\r\n  \t<div class=\"icon-box-wrapper\">\r\n\t\t\r\n\t\t\t<div class=\"icon-text\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t<h5 class=\"icon-box-title \">\r\n\t\t\t\t\t\t\t24\/7 Support\t\t\t\t\t<\/h5>\r\n\t\t\t\t\t<div class=\"content\">Lorem Ipsum is simply dummy text of the printing and typesetting industry.<\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\r\n\t\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"clearfix\"><\/div>\r\n\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-650d00c elementor-widget elementor-widget-tm-ele-button\" data-id=\"650d00c\" data-element_type=\"widget\" data-widget_type=\"tm-ele-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-button btn-view-details \">\r\n\t<a  href=\"#\" \r\n\t\t\t\t\t\tclass=\"btn btn-theme-colored1 btn-flat\">\r\n\r\n\t\t\r\n\t\t\r\n\t\t<span>\r\n\t\tExplore now\t\t<\/span>\r\n\r\n\t\t\t<\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-35eba8e tm-bg-color-over-image\" data-id=\"35eba8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-739b5e4 elementor-widget elementor-widget-tm-ele-iconbox\" data-id=\"739b5e4\" data-element_type=\"widget\" data-widget_type=\"tm-ele-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-icon-box icon-box icon-top tm-iconbox-icontype-font-icon icon-position-icon-top animate-icon-on-hover animate-icon-rotate-y\" >\r\n\t\r\n  \t<div class=\"icon-box-wrapper\">\r\n\t\t\r\n\t\t<div class=\"icon-wrapper\">\r\n\t\t<a class=\"icon icon-type-font-icon icon-size-default icon-default-bg icon-circled\"\r\n\r\n\t\t\t\t\t\t\t\t>\r\n\t\t\t<i aria-hidden=\"true\" class=\" flaticon-agency-satisfaction\"><\/i>\t\t<\/a>\r\n\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"icon-text\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t<h5 class=\"icon-box-title \">\r\n\t\t\t\t\t\t\tTrusted by <br\/> Clients\t\t\t\t\t<\/h5>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\r\n\t\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"clearfix\"><\/div>\r\n\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d27648b elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"6d27648b\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7e7b2568 tm-bg-color-over-image\" data-id=\"7e7b2568\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-433bf459 elementor-widget elementor-widget-tm-ele-block-features\" data-id=\"433bf459\" data-element_type=\"widget\" data-widget_type=\"tm-ele-block-features.skin-style4\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Feature Block -->\r\n<div class=\"feature-block feature-current-item-style4 \">\r\n  <div class=\"inner-box\">\r\n    <div class=\"image-box\">\r\n      <figure class=\"image\">\r\n                <img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/bg23-672x448.jpg\" alt=\"Image\">\r\n              <\/figure>\r\n      <div class=\"info-box\">\r\n      \r\n\r\n\t\r\n\t<div class=\"icon\">\r\n\t\t<i class=\" flaticon-agency-color-sample\"><\/i>\r\n\t<\/div>\r\n\r\n\t      \r\n\t\t\t\t<h4 class=\"feature-title \">\r\n\t\t\t\t\t\t\tLeader in Digital Marketing\t\t\t\t\t<\/h4>\r\n\t\t      <\/div>\r\n    <\/div>\r\n    <div class=\"overlay-content\">\r\n      <div class=\"info-box\">\r\n      \r\n\r\n\t\r\n\t<div class=\"icon\">\r\n\t\t<i class=\" flaticon-agency-color-sample\"><\/i>\r\n\t<\/div>\r\n\r\n\t      \r\n\t\t\t\t<h4 class=\"feature-title \">\r\n\t\t\t\t\t\t\tLeader in Digital Marketing\t\t\t\t\t<\/h4>\r\n\t\t      \r\n\t\t\t<div class=\"feature-details\">Write a short description, that will describe the title or something informational and useful.<\/div>      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c4d36df tm-bg-color-over-image\" data-id=\"4c4d36df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a433791 elementor-widget elementor-widget-tm-ele-block-features\" data-id=\"6a433791\" data-element_type=\"widget\" data-widget_type=\"tm-ele-block-features.skin-style4\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Feature Block -->\r\n<div class=\"feature-block feature-current-item-style4 \">\r\n  <div class=\"inner-box\">\r\n    <div class=\"image-box\">\r\n      <figure class=\"image\">\r\n                <img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/bg21-672x448.jpg\" alt=\"Image\">\r\n              <\/figure>\r\n      <div class=\"info-box\">\r\n      \r\n\r\n\t\r\n\t<div class=\"icon\">\r\n\t\t<i class=\" flaticon-agency-trophy\"><\/i>\r\n\t<\/div>\r\n\r\n\t      \r\n\t\t\t\t<h4 class=\"feature-title \">\r\n\t\t\t\t\t\t\tHighest Success<br> Rates\t\t\t\t\t<\/h4>\r\n\t\t      <\/div>\r\n    <\/div>\r\n    <div class=\"overlay-content\">\r\n      <div class=\"info-box\">\r\n      \r\n\r\n\t\r\n\t<div class=\"icon\">\r\n\t\t<i class=\" flaticon-agency-trophy\"><\/i>\r\n\t<\/div>\r\n\r\n\t      \r\n\t\t\t\t<h4 class=\"feature-title \">\r\n\t\t\t\t\t\t\tHighest Success<br> Rates\t\t\t\t\t<\/h4>\r\n\t\t      \r\n\t\t\t<div class=\"feature-details\">Write a short description, that will describe the title or something informational and useful.<\/div>      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1474a9bf tm-bg-color-over-image\" data-id=\"1474a9bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26847b5b elementor-widget elementor-widget-tm-ele-block-features\" data-id=\"26847b5b\" data-element_type=\"widget\" data-widget_type=\"tm-ele-block-features.skin-style4\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Feature Block -->\r\n<div class=\"feature-block feature-current-item-style4 \">\r\n  <div class=\"inner-box\">\r\n    <div class=\"image-box\">\r\n      <figure class=\"image\">\r\n                <img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/bg20-672x448.jpg\" alt=\"Image\">\r\n              <\/figure>\r\n      <div class=\"info-box\">\r\n      \r\n\r\n\t\r\n\t<div class=\"icon\">\r\n\t\t<i class=\" flaticon-agency-satisfaction\"><\/i>\r\n\t<\/div>\r\n\r\n\t      \r\n\t\t\t\t<h4 class=\"feature-title \">\r\n\t\t\t\t\t\t\tQuality Marketing Solutions\t\t\t\t\t<\/h4>\r\n\t\t      <\/div>\r\n    <\/div>\r\n    <div class=\"overlay-content\">\r\n      <div class=\"info-box\">\r\n      \r\n\r\n\t\r\n\t<div class=\"icon\">\r\n\t\t<i class=\" flaticon-agency-satisfaction\"><\/i>\r\n\t<\/div>\r\n\r\n\t      \r\n\t\t\t\t<h4 class=\"feature-title \">\r\n\t\t\t\t\t\t\tQuality Marketing Solutions\t\t\t\t\t<\/h4>\r\n\t\t      \r\n\t\t\t<div class=\"feature-details\">Write a short description, that will describe the title or something informational and useful.<\/div>      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a60a54 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"3a60a54\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f06fe7 tm-bg-color-over-image\" data-id=\"4f06fe7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3174568 elementor-widget elementor-widget-tm-ele-moving-text\" data-id=\"3174568\" data-element_type=\"widget\" data-settings=\"{&quot;text&quot;:&quot;Web Design Agency . App Development Agency&quot;,&quot;divider_custom&quot;:&quot;.&quot;,&quot;link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;start_point_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;start_point_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-10,&quot;sizes&quot;:[]},&quot;end_point_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;end_point_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"tm-ele-moving-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-moving-text scroll_animation  clone_text add_divider \" data-backspace-count=\"\" data-d-type=\"custom\" data-d-custom=\".\" data-type-svg=\"mascot_line_simple\" data-text=\"Web Design Agency . App Development Agency\">\r\n\t\t\t<div class=\"simple_line\"><\/div>\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12d7d1e7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"12d7d1e7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50746fed tm-bg-color-over-image\" data-id=\"50746fed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-52e76add elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"52e76add\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b1211a2 tm-bg-color-over-image\" data-id=\"b1211a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-794a4fe9 horizontal-line-align-left vertical-line-align-bottom elementor-widget elementor-widget-tm-ele-section-title\" data-id=\"794a4fe9\" data-element_type=\"widget\" data-widget_type=\"tm-ele-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-section-title section-title \">\r\n\t<div class=\"title-wrapper\">\r\n\t\t\t\t\t\t<h6 class=\"subtitle \">\r\n\r\n\t\t\r\n\t\tOur Services\t<\/h6>\r\n\t\t\t\t<h2 class=\"title \">\r\n\r\n\t\t\r\n\t\t\t\t<span class=\"title-part1 \">What We Offer<\/span>\r\n\t\t\t\t\r\n\t\t\r\n\t<\/h2>\r\n\t<div class=\"title-seperator-line\"><\/div>\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ecf28ae tm-bg-color-over-image\" data-id=\"5ecf28ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6db651c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"6db651c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68b839 tm-bg-color-over-image\" data-id=\"68b839\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a3dfbef elementor-widget elementor-widget-tm-ele-text-editor\" data-id=\"4a3dfbef\" data-element_type=\"widget\" data-widget_type=\"tm-ele-text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-text-editor\">\r\n\t\t<p>Lorem Ipsum. Proin gravida nibh vel velit auctor aliquet. Aenean solldin, lorem is simply free text quis bibendum<\/p>\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-614dcda2 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"614dcda2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4891e2c8 tm-bg-color-over-image\" data-id=\"4891e2c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74fbb2c2 elementor-widget elementor-widget-tm-ele-cpt-services\" data-id=\"74fbb2c2\" data-element_type=\"widget\" data-widget_type=\"tm-ele-cpt-services.skin-style-current-theme7\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t<div class=\"tm-sc-services tm-sc-services-grid border-radius-around-box\">\r\n\t\t\r\n\t\r\n\t\t<!-- Isotope Gallery Grid -->\r\n\t\t<div id=\"services-holder-176119\" class=\"isotope-layout grid-2 gutter-15 clearfix\">\r\n\t\t\t<div class=\"isotope-layout-inner\">\r\n\r\n                <!-- the loop -->\r\n                                                <div class=\"isotope-item \">\r\n                    \r\n<div id=\"post-11708\" class=\"post-11708 services type-services status-publish has-post-thumbnail hentry\">\r\n<div class=\"service-item-current-style7\">\r\n  <div class=\"service-inner \">\r\n    <div class=\"image\">\r\n      <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"180\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/bg22-150x180.jpg\" class=\"img-fullwidth wp-post-image\" alt=\"\" \/>      <span class=\"icon\">W<\/span>\r\n    <\/div>\r\n    \t\t<h4 class=\"title feature-title\"><a href=\"#\">Web Designing<\/a><\/h4>\r\n\t\t                      <p class=\"excerpt service-details\">\r\n            Lorem Ipsum is simply dummy text of the printing and typesetting industry.          <\/p>\r\n                <\/div>\r\n<\/div>\r\n<\/div>                <\/div>\r\n                                                <div class=\"isotope-item \">\r\n                    \r\n<div id=\"post-11707\" class=\"post-11707 services type-services status-publish has-post-thumbnail hentry\">\r\n<div class=\"service-item-current-style7\">\r\n  <div class=\"service-inner \">\r\n    <div class=\"image\">\r\n      <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"180\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/bg32-150x180.jpg\" class=\"img-fullwidth wp-post-image\" alt=\"\" \/>      <span class=\"icon\">A<\/span>\r\n    <\/div>\r\n    \t\t<h4 class=\"title feature-title\"><a href=\"#\">App Development<\/a><\/h4>\r\n\t\t                      <p class=\"excerpt service-details\">\r\n            Lorem Ipsum is simply dummy text of the printing and typesetting industry.          <\/p>\r\n                <\/div>\r\n<\/div>\r\n<\/div>                <\/div>\r\n                                                <div class=\"isotope-item \">\r\n                    \r\n<div id=\"post-11706\" class=\"post-11706 services type-services status-publish has-post-thumbnail hentry\">\r\n<div class=\"service-item-current-style7\">\r\n  <div class=\"service-inner \">\r\n    <div class=\"image\">\r\n      <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"180\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/bg20-150x180.jpg\" class=\"img-fullwidth wp-post-image\" alt=\"\" \/>      <span class=\"icon\">W<\/span>\r\n    <\/div>\r\n    \t\t<h4 class=\"title feature-title\"><a href=\"#\">Web Application<\/a><\/h4>\r\n\t\t                      <p class=\"excerpt service-details\">\r\n            Lorem Ipsum is simply dummy text of the printing and typesetting industry.          <\/p>\r\n                <\/div>\r\n<\/div>\r\n<\/div>                <\/div>\r\n                                                <div class=\"isotope-item \">\r\n                    \r\n<div id=\"post-11704\" class=\"post-11704 services type-services status-publish has-post-thumbnail hentry\">\r\n<div class=\"service-item-current-style7\">\r\n  <div class=\"service-inner \">\r\n    <div class=\"image\">\r\n      <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"180\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/bg29-150x180.jpg\" class=\"img-fullwidth wp-post-image\" alt=\"\" \/>      <span class=\"icon\">W<\/span>\r\n    <\/div>\r\n    \t\t<h4 class=\"title feature-title\"><a href=\"#\">Web Development<\/a><\/h4>\r\n\t\t                      <p class=\"excerpt service-details\">\r\n            Lorem Ipsum is simply dummy text of the printing and typesetting industry.          <\/p>\r\n                <\/div>\r\n<\/div>\r\n<\/div>                <\/div>\r\n                                <!-- end of the loop -->\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d01a862 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"1d01a862\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d1cce0a tm-bg-color-over-image\" data-id=\"5d1cce0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-546ddc3d elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"546ddc3d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-289aaefb tm-bg-color-over-image\" data-id=\"289aaefb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2bf046ea tm-bg-color-over-image\" data-id=\"2bf046ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d78057b horizontal-line-align-left vertical-line-align-bottom elementor-widget elementor-widget-tm-ele-section-title\" data-id=\"7d78057b\" data-element_type=\"widget\" data-widget_type=\"tm-ele-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-section-title section-title center\">\r\n\t<div class=\"title-wrapper\">\r\n\t\t\t\t\t\t<p class=\"subtitle \">\r\n\r\n\t\t\r\n\t\tOur work process\t<\/p>\r\n\t\t\t\t<h2 class=\"title \">\r\n\r\n\t\t\r\n\t\t\t\t<span class=\"title-part1 \">Get Your  Easy Steps  to Process<\/span>\r\n\t\t\t\t\r\n\t\t\r\n\t<\/h2>\r\n\t<div class=\"title-seperator-line\"><\/div>\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2af080bd tm-bg-color-over-image\" data-id=\"2af080bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-11a35f1a elementor-widget elementor-widget-tm-ele-working-steps\" data-id=\"11a35f1a\" data-element_type=\"widget\" data-widget_type=\"tm-ele-working-steps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-sc-working-steps working-steps-horizontal working-steps-items-3 \">\r\n\t\t\t<div class=\"working-steps-bg-holder\" ><\/div>\r\n\t\t\t<div class=\"working-steps-inner clearfix\">\r\n\t<div class=\"tm-sc-working-steps-item image-full-bg elementor-repeater-item-a75a440\">\r\n\t<div class=\"working-steps-item-inner\">\r\n\t\t<div class=\"image-holder-wrapper\">\r\n\t\t\t<div class=\"image-holder\">\r\n\t\t\t\t<div class=\"image-holder-inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-flaticon elementor-icon\"><i aria-hidden=\"true\" class=\" flaticon-agency-color-sample\"><\/i><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"tag\">01<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"content-holder\">\r\n\t\t\t\t\t\t\t<div class=\"title-holder\">\r\n\t\t\t\t\t<h4 class=\"title\">Share Your Concept<\/h4>\t\t\t\t<\/div>\r\n\t\t\t\r\n\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<div class=\"arrow-symbol-img\">\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/arrow1.png\" alt=\"Image\">\r\n\t\t\t\t<\/div>\r\n\t<\/div><div class=\"tm-sc-working-steps-item image-full-bg elementor-repeater-item-0215aa6\">\r\n\t<div class=\"working-steps-item-inner\">\r\n\t\t<div class=\"image-holder-wrapper\">\r\n\t\t\t<div class=\"image-holder\">\r\n\t\t\t\t<div class=\"image-holder-inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-flaticon elementor-icon\"><i aria-hidden=\"true\" class=\" flaticon-agency-campaign\"><\/i><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"tag\">01<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"content-holder\">\r\n\t\t\t\t\t\t\t<div class=\"title-holder\">\r\n\t\t\t\t\t<h4 class=\"title\">Let\u2019s Start Development<\/h4>\t\t\t\t<\/div>\r\n\t\t\t\r\n\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<div class=\"arrow-symbol-img\">\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/arrow1.png\" alt=\"Image\">\r\n\t\t\t\t<\/div>\r\n\t<\/div><div class=\"tm-sc-working-steps-item image-full-bg elementor-repeater-item-7801afb\">\r\n\t<div class=\"working-steps-item-inner\">\r\n\t\t<div class=\"image-holder-wrapper\">\r\n\t\t\t<div class=\"image-holder\">\r\n\t\t\t\t<div class=\"image-holder-inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-flaticon elementor-icon\"><i aria-hidden=\"true\" class=\" flaticon-agency-trophy\"><\/i><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"tag\">01<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"content-holder\">\r\n\t\t\t\t\t\t\t<div class=\"title-holder\">\r\n\t\t\t\t\t<h4 class=\"title\">Ready to Launch<\/h4>\t\t\t\t<\/div>\r\n\t\t\t\r\n\r\n\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<div class=\"arrow-symbol-img\">\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/arrow1.png\" alt=\"Image\">\r\n\t\t\t\t<\/div>\r\n\t<\/div>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ddb439 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"19ddb439\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f775d61 tm-bg-color-over-image\" data-id=\"3f775d61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6da1f0a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"6da1f0a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-743b6ccc tm-bg-color-over-image\" data-id=\"743b6ccc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-163a2969 horizontal-line-align-left vertical-line-align-bottom elementor-widget elementor-widget-tm-ele-section-title\" data-id=\"163a2969\" data-element_type=\"widget\" data-widget_type=\"tm-ele-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-section-title section-title \">\r\n\t<div class=\"title-wrapper\">\r\n\t\t\t\t\t\t<h6 class=\"subtitle \">\r\n\r\n\t\t\r\n\t\tWhy Choose Us\t<\/h6>\r\n\t\t\t\t<h2 class=\"title \">\r\n\r\n\t\t\r\n\t\t\t\t<span class=\"title-part1 \">We Made Things Easier For Your Business<\/span>\r\n\t\t\t\t\r\n\t\t\r\n\t<\/h2>\r\n\t<div class=\"title-seperator-line\"><\/div>\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b01114b elementor-widget elementor-widget-tm-ele-list\" data-id=\"1b01114b\" data-element_type=\"widget\" data-widget_type=\"tm-ele-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"tm-sc-list \">\r\n\t<li class=\"no-action\">\r\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t<span>\r\n\tLorem Ipsum is simply dummy text.<\/span><\/li>\t<li class=\"\">\r\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t<span>\r\n\tLorem Ipsum is simply dummy text.<\/span><\/li>\t<li class=\"\">\r\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t<span>\r\n\tLorem Ipsum is simply dummy text.<\/span><\/li><\/ul>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1050213 elementor-widget elementor-widget-tm-ele-progress-bar\" data-id=\"1050213\" data-element_type=\"widget\" data-widget_type=\"tm-ele-progress-bar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-progress-bar progress-bar-floating-percent \" data-percent=\"80\" data-unit-left=\"\" data-unit-right=\"%\">\r\n\t<div class=\"progress-title-holder\">\r\n\t\t<h5 class=\"pb-title\">APP DEVELOPMENT<\/h5>\r\n\t\t<span class=\"percent\"><span class=\"symbol-left\"><\/span><span class=\"value\">80<\/span><span class=\"symbol-right\">%<\/span><\/span>\r\n\t<\/div>\r\n\t<div class=\"progress-holder\">\r\n\t\t<div class=\"progress-content\"><\/div>\r\n\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dcc6439 elementor-widget elementor-widget-tm-ele-progress-bar\" data-id=\"1dcc6439\" data-element_type=\"widget\" data-widget_type=\"tm-ele-progress-bar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-progress-bar progress-bar-floating-percent \" data-percent=\"90\" data-unit-left=\"\" data-unit-right=\"%\">\r\n\t<div class=\"progress-title-holder\">\r\n\t\t<h5 class=\"pb-title\">WEB DESIGNING<\/h5>\r\n\t\t<span class=\"percent\"><span class=\"symbol-left\"><\/span><span class=\"value\">90<\/span><span class=\"symbol-right\">%<\/span><\/span>\r\n\t<\/div>\r\n\t<div class=\"progress-holder\">\r\n\t\t<div class=\"progress-content\"><\/div>\r\n\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27f7f0ac elementor-widget elementor-widget-tm-ele-floating-objects\" data-id=\"27f7f0ac\" data-element_type=\"widget\" data-widget_type=\"tm-ele-floating-objects.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-ele-floating-objects \">\r\n\t<span class=\"each-object elementor-repeater-item-0a0d67a tm-animation-floating \" style=\"background-image: url(https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/plane3.png); z-index: -1;\"><\/span>\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1719587f tm-bg-color-over-image\" data-id=\"1719587f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e92dff7 elementor-hidden-mobile elementor-widget elementor-widget-tm-ele-image-with-rotated-text\" data-id=\"2e92dff7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"tm-ele-image-with-rotated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-image-with-rotated-text  text-position-bottom-right\">\r\n\t<div class=\"image-text-wrapper\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\r\n\t\t<div class=\"image-inner\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"text-holder\" style=\"-webkit-transform: rotate(-90deg); -ms-transform: rotate(-90deg); transform: rotate(-90deg); z-index: 2; -webkit-text-stroke: unset;\">\r\n\t\t\t\t\t<div class=\"text-inner\">\r\n\t\t\t\t\t\t<div class=\"text tm-textillate-animation\">Trusted by clients<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t<\/div>\r\n<\/div>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5724719d tm-bg-color-over-image\" data-id=\"5724719d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b7682c3 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"4b7682c3\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"421\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/lines.png\" class=\"attachment-full size-full wp-image-42958\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/lines.png 452w, https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/04\/lines-300x279.png 300w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e846736 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"5e846736\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1792\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design.jpg\" class=\"attachment-full size-full wp-image-47153\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design.jpg 2560w, https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design-300x210.jpg 300w, https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design-1024x717.jpg 1024w, https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design-768x538.jpg 768w, https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design-1536x1075.jpg 1536w, https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design-2048x1434.jpg 2048w, https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/08\/Web-Design-600x420.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1178d3ca elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"1178d3ca\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67aa8537 tm-bg-color-over-image\" data-id=\"67aa8537\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-151d1016 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"151d1016\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-30696779 tm-bg-color-over-image\" data-id=\"30696779\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-904834b horizontal-line-align-left vertical-line-align-bottom elementor-widget elementor-widget-tm-ele-section-title\" data-id=\"904834b\" data-element_type=\"widget\" data-widget_type=\"tm-ele-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-section-title section-title \">\r\n\t<div class=\"title-wrapper\">\r\n\t\t\t\t\t\t<h6 class=\"subtitle \">\r\n\r\n\t\t\r\n\t\tWe can help you\t<\/h6>\r\n\t\t\t\t<h2 class=\"title \">\r\n\r\n\t\t\r\n\t\t\t\t<span class=\"title-part1 \">We\u2019re standout experts in the business<\/span>\r\n\t\t\t\t\r\n\t\t\r\n\t<\/h2>\r\n\t<div class=\"title-seperator-line\"><\/div>\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5c1c3916 tm-bg-color-over-image\" data-id=\"5c1c3916\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6dfbe6e1 tm-bg-color-over-image\" data-id=\"6dfbe6e1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7f71c elementor-widget elementor-widget-spacer\" data-id=\"3d7f71c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e10c7b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"5e10c7b0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7b167067 tm-bg-color-over-image\" data-id=\"7b167067\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-190d9d4f elementor-widget elementor-widget-tm-ele-funfact-counter\" data-id=\"190d9d4f\" data-element_type=\"widget\" data-widget_type=\"tm-ele-funfact-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"tm-sc-funfact funfact-iconleft \">\r\n\t\t<div class=\"funfact-inner\">\r\n\t\t\t<div class=\"element-left\">\r\n\t\t\t\t\t\t\t\t<div class=\"funfact-icon\">\r\n<i aria-hidden=\"true\" class=\" flaticon-agency-satisfaction\"><\/i><\/div>\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\r\n\t\t\t<div class=\"details\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"counter \">\r\n\t<span class=\"animate-number\" data-value=\"500\" data-animation-duration=\"1500\">0<\/span><\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\r\n\r\n<h5 class=\"title \">Satisfied Customers<\/h5>\r\n<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5b3620de tm-bg-color-over-image\" data-id=\"5b3620de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61cb5077 elementor-widget elementor-widget-tm-ele-funfact-counter\" data-id=\"61cb5077\" data-element_type=\"widget\" data-widget_type=\"tm-ele-funfact-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"tm-sc-funfact funfact-iconleft \">\r\n\t\t<div class=\"funfact-inner\">\r\n\t\t\t<div class=\"element-left\">\r\n\t\t\t\t\t\t\t\t<div class=\"funfact-icon\">\r\n<i aria-hidden=\"true\" class=\" flaticon-agency-design\"><\/i><\/div>\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\r\n\t\t\t<div class=\"details\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"counter \">\r\n\t<span class=\"animate-number\" data-value=\"1253\" data-animation-duration=\"1500\">0<\/span><\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\r\n\r\n<h5 class=\"title \">Completed Projects<\/h5>\r\n<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fda8716 tm-bg-color-over-image\" data-id=\"fda8716\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17f76c1 elementor-widget elementor-widget-tm-ele-funfact-counter\" data-id=\"17f76c1\" data-element_type=\"widget\" data-widget_type=\"tm-ele-funfact-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"tm-sc-funfact funfact-iconleft \">\r\n\t\t<div class=\"funfact-inner\">\r\n\t\t\t<div class=\"element-left\">\r\n\t\t\t\t\t\t\t\t<div class=\"funfact-icon\">\r\n<i aria-hidden=\"true\" class=\" flaticon-agency-reputation\"><\/i><\/div>\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\r\n\t\t\t<div class=\"details\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"counter \">\r\n\t<span class=\"animate-number\" data-value=\"473\" data-animation-duration=\"1500\">0<\/span><\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\r\n\r\n<h5 class=\"title \">Expert Team Members<\/h5>\r\n<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c35ebd4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"5c35ebd4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4b30a758 tm-bg-color-over-image\" data-id=\"4b30a758\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36932535 horizontal-line-align-left vertical-line-align-bottom elementor-widget elementor-widget-tm-ele-section-title\" data-id=\"36932535\" data-element_type=\"widget\" data-widget_type=\"tm-ele-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-section-title section-title \">\r\n\t<div class=\"title-wrapper\">\r\n\t\t\t\t\t\t<h6 class=\"subtitle \">\r\n\r\n\t\t\r\n\t\tTestimonials\t<\/h6>\r\n\t\t\t\t<h2 class=\"title \">\r\n\r\n\t\t\r\n\t\t\t\t<span class=\"title-part1 \">What Our Client Say's<\/span>\r\n\t\t\t\t\r\n\t\t\r\n\t<\/h2>\r\n\t<div class=\"title-seperator-line\"><\/div>\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-502f3388 elementor-widget elementor-widget-tm-ele-text-editor\" data-id=\"502f3388\" data-element_type=\"widget\" data-widget_type=\"tm-ele-text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-text-editor\">\r\n\t\tLorem Ipsum is simply dummy text of the printing and typesetting industry. Lorem Ipsum has been the industry's standard dummy text ever since the 1500s.\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-775b0c56 tm-bg-color-over-image\" data-id=\"775b0c56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ea811d7 tm-bg-color-over-image\" data-id=\"7ea811d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-576374d5 elementor-widget elementor-widget-tm-ele-cpt-testimonials\" data-id=\"576374d5\" data-element_type=\"widget\" data-widget_type=\"tm-ele-cpt-testimonials.skin-style-current-theme2\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t<div class=\"tm-sc-testimonials tm-sc-testimonials-grid tm-sc-skin-style-current-theme2 testimonial-has-custom-quote-icon custom-quote-icon-left \">\r\n\t\t\r\n\t\r\n\t\t<!-- Isotope Gallery Grid -->\r\n\t\t<div id=\"testimonials-holder-642700\" class=\"isotope-layout grid-3 gutter-15 clearfix\">\r\n\t\t\t<div class=\"isotope-layout-inner\">\r\n\r\n                <!-- the loop -->\r\n                                                <div class=\"isotope-item tall\">\r\n                    <div class=\"testimonial-block-two\">\r\n  <div class=\"inner-box\">\r\n    <div class=\"image-box\">\r\n              <div class=\"author-text\">\r\n\t\t\tLorem Ipsum is simply dummy text of the printing and typesetting industry. Lorem Ipsum has been the industry&#039;s standard dummy text ever since\t<\/div>            <div class=\"info-box\">\r\n                  <h5 class=\"name\">Thomas Alen<\/h5>\r\n                          <span class=\"job-position\"><\/span>\r\n                <span class=\"icon icon-quote\"><\/span>\r\n      <\/div>\r\n      <div class=\"rating\">\r\n                  <div class=\"star-rating\">\r\n\t<span style=\"width: 0%\"><\/span>\r\n<\/div>              <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>                <\/div>\r\n                                                <div class=\"isotope-item tall\">\r\n                    <div class=\"testimonial-block-two\">\r\n  <div class=\"inner-box\">\r\n    <div class=\"image-box\">\r\n              <div class=\"author-text\">\r\n\t\t\tLorem Ipsum is simply dummy text of the printing and typesetting industry. Lorem Ipsum has been the industry&#039;s standard dummy text ever since\t<\/div>            <div class=\"info-box\">\r\n                  <h5 class=\"name\">Jack Winger<\/h5>\r\n                          <span class=\"job-position\"><\/span>\r\n                <span class=\"icon icon-quote\"><\/span>\r\n      <\/div>\r\n      <div class=\"rating\">\r\n                  <div class=\"star-rating\">\r\n\t<span style=\"width: 0%\"><\/span>\r\n<\/div>              <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>                <\/div>\r\n                                                <div class=\"isotope-item tall\">\r\n                    <div class=\"testimonial-block-two\">\r\n  <div class=\"inner-box\">\r\n    <div class=\"image-box\">\r\n              <div class=\"author-text\">\r\n\t\t\tLorem Ipsum is simply dummy text of the printing and typesetting industry. Lorem Ipsum has been the industry&#039;s standard dummy text ever since\t<\/div>            <div class=\"info-box\">\r\n                  <h5 class=\"name\">Jessica Taylor<\/h5>\r\n                          <span class=\"job-position\"><\/span>\r\n                <span class=\"icon icon-quote\"><\/span>\r\n      <\/div>\r\n      <div class=\"rating\">\r\n                  <div class=\"star-rating\">\r\n\t<span style=\"width: 0%\"><\/span>\r\n<\/div>              <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>                <\/div>\r\n                                <!-- end of the loop -->\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a0219c7 elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"1a0219c7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56a20a95 tm-bg-color-over-image\" data-id=\"56a20a95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1ab737d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"1ab737d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5b4b5739 tm-bg-color-over-image\" data-id=\"5b4b5739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b29788 elementor-widget elementor-widget-tm-ele-clients-logo\" data-id=\"3b29788\" data-element_type=\"widget\" data-widget_type=\"tm-ele-clients-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"tm-sc-clients-logo clients-carousel clients-animation-grayscale\">\r\n\t\t<div class=\"owl-carousel owl-theme tm-owl-carousel-5col\" data-autoplay=\"true\" data-loop=\"true\" data-duration=\"6000\" data-smartspeed=\"300\" data-margin=\"30\" data-laptop_large=\"4\" data-tablet_extra=\"3\">\r\n\t\t\t<!-- the loop -->\r\n\t\t\t\t\t\t<div class=\"slide-owl-wrap\">\r\n\t\t\t\t<div class=\"each-logo\">\r\n\t<img loading=\"lazy\" decoding=\"async\" class=\"thumb\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/clients-logo6.png\"  width=\"700\" height=\"256\" alt=\"\"><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"slide-owl-wrap\">\r\n\t\t\t\t<div class=\"each-logo\">\r\n\t<img loading=\"lazy\" decoding=\"async\" class=\"thumb\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/clients-logo5.png\"  width=\"700\" height=\"256\" alt=\"\"><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"slide-owl-wrap\">\r\n\t\t\t\t<div class=\"each-logo\">\r\n\t<img loading=\"lazy\" decoding=\"async\" class=\"thumb\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/clients-logo4.png\"  width=\"700\" height=\"256\" alt=\"\"><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"slide-owl-wrap\">\r\n\t\t\t\t<div class=\"each-logo\">\r\n\t<img loading=\"lazy\" decoding=\"async\" class=\"thumb\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/clients-logo3.png\"  width=\"700\" height=\"256\" alt=\"\"><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"slide-owl-wrap\">\r\n\t\t\t\t<div class=\"each-logo\">\r\n\t<img loading=\"lazy\" decoding=\"async\" class=\"thumb\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/clients-logo7.png\"  width=\"700\" height=\"256\" alt=\"\"><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"slide-owl-wrap\">\r\n\t\t\t\t<div class=\"each-logo\">\r\n\t<img loading=\"lazy\" decoding=\"async\" class=\"thumb\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2023\/01\/clients-logo1.png\"  width=\"700\" height=\"256\" alt=\"\"><\/div>\t\t\t<\/div>\r\n\t\t\t\t\t\t<!-- end of the loop -->\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6413a45 elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"6413a45\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c82af6 tm-bg-color-over-image\" data-id=\"3c82af6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e9a728 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"1e9a728\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-bbaf8d3 tm-bg-color-over-image\" data-id=\"bbaf8d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-8bc30a5 tm-bg-color-over-image\" data-id=\"8bc30a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2890063 horizontal-line-align-left vertical-line-align-bottom elementor-widget elementor-widget-tm-ele-section-title\" data-id=\"2890063\" data-element_type=\"widget\" data-widget_type=\"tm-ele-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-section-title section-title center\">\r\n\t<div class=\"title-wrapper\">\r\n\t\t\t\t\t\t<h6 class=\"subtitle \">\r\n\r\n\t\t\r\n\t\tFrom the Blog\t<\/h6>\r\n\t\t\t\t<h2 class=\"title \">\r\n\r\n\t\t\r\n\t\t\t\t<span class=\"title-part1 \">News & Articles<\/span>\r\n\t\t\t\t\r\n\t\t\r\n\t<\/h2>\r\n\t<div class=\"title-seperator-line\"><\/div>\t\t\t\t\t\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-dae610f tm-bg-color-over-image\" data-id=\"dae610f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2ef8a6 elementor-widget elementor-widget-tm-ele-blog\" data-id=\"c2ef8a6\" data-element_type=\"widget\" data-widget_type=\"tm-ele-blog.skin-style-current-theme1\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"tm-sc-blog tm-sc-blog-grid \">\r\n\t\t\r\n\t\r\n\t\t<!-- Isotope Gallery Grid -->\r\n\t\t<div id=\"blog-holder-249914\" class=\"isotope-layout grid-3 gutter-15 clearfix\">\r\n\t\t\t<div class=\"isotope-layout-inner\">\r\n\r\n\t\t\t\t<!-- the loop -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-item seo-marketing ui-ux-design\">\r\n\t\t\t\t\t<div class=\"isotope-item-inner\">\r\n\t\t\t\t\t\t<article class=\"post-772 post type-post status-publish format-standard has-post-thumbnail hentry category-seo-marketing category-ui-ux-design tag-agency\">\r\n\t<!-- News Block -->\r\n<div class=\"blog-item-current-style1\">\r\n      <div class=\"entry-header\">\r\n      <div class=\"post-thumb lightgallery-lightbox\">\r\n\t\r\n\t<div class=\"post-thumb-inner\">\r\n\t\t<div class=\"thumb\">\r\n\t\t\t<img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2022\/12\/bg7-672x448.jpg\" alt=\"Top crypto exchange influencers in china\"\/>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<\/div>    <\/div>\r\n    <div class=\"entry-content\">\r\n\r\n          \t<ul class=\"entry-meta list-inline\">\r\n\t\t\t\t<li class=\"list-inline-item author\"><i class=\"fa fa-user-circle-o\"><\/i> <span class=\"byline\">By <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/author\/admin\/\" rel=\"author\">admin<\/a><\/span><\/span><\/li>\r\n\t\t\t\t<li class=\"list-inline-item comments\"><i class=\"fa fa-comments-o\"><\/i> <a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/31\/top-crypto-exchange-influencers-in-china\/#comments\">1 Comment<\/a><\/li>\r\n\t\t<\/ul>\r\n\t    \r\n          <div class=\"title-holder\">\r\n        <h4 class=\"entry-title\"><a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/31\/top-crypto-exchange-influencers-in-china\/\" rel=\"bookmark\">Top crypto exchange influencers in china<\/a><\/h4>      <\/div>\r\n    \r\n          <div class=\"post-excerpt\">\r\n                  <div class=\"mascot-post-excerpt\">Duis aute irure dolor lipsum simply free text the local markets<\/div>              <\/div>\r\n    \r\n    \t\t\t<div class=\"btn-view-details post-btn-readmore \">\r\n    <a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/31\/top-crypto-exchange-influencers-in-china\/\"\r\n      class=\"btn btn-plain-text-with-arrow-right\">\r\n      Read More    <\/a>\r\n<\/div>    \r\n  <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n<\/div><\/article>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-item cloud-solution web-technologies\">\r\n\t\t\t\t\t<div class=\"isotope-item-inner\">\r\n\t\t\t\t\t\t<article class=\"post-771 post type-post status-publish format-standard has-post-thumbnail hentry category-cloud-solution category-web-technologies tag-digital\">\r\n\t<!-- News Block -->\r\n<div class=\"blog-item-current-style1\">\r\n      <div class=\"entry-header\">\r\n      <div class=\"post-thumb lightgallery-lightbox\">\r\n\t\r\n\t<div class=\"post-thumb-inner\">\r\n\t\t<div class=\"thumb\">\r\n\t\t\t<img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2022\/12\/bg1-672x448.jpg\" alt=\"Necessity may give us best virtual court\"\/>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<\/div>    <\/div>\r\n    <div class=\"entry-content\">\r\n\r\n          \t<ul class=\"entry-meta list-inline\">\r\n\t\t\t\t<li class=\"list-inline-item author\"><i class=\"fa fa-user-circle-o\"><\/i> <span class=\"byline\">By <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/author\/admin\/\" rel=\"author\">admin<\/a><\/span><\/span><\/li>\r\n\t\t\t\t<li class=\"list-inline-item comments\"><i class=\"fa fa-comments-o\"><\/i> <a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/31\/necessity-may-give-us-best-virtual-court\/#comments\">1 Comment<\/a><\/li>\r\n\t\t<\/ul>\r\n\t    \r\n          <div class=\"title-holder\">\r\n        <h4 class=\"entry-title\"><a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/31\/necessity-may-give-us-best-virtual-court\/\" rel=\"bookmark\">Necessity may give us best virtual court<\/a><\/h4>      <\/div>\r\n    \r\n          <div class=\"post-excerpt\">\r\n                  <div class=\"mascot-post-excerpt\">Duis aute irure dolor lipsum simply free text the local markets<\/div>              <\/div>\r\n    \r\n    \t\t\t<div class=\"btn-view-details post-btn-readmore \">\r\n    <a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/31\/necessity-may-give-us-best-virtual-court\/\"\r\n      class=\"btn btn-plain-text-with-arrow-right\">\r\n      Read More    <\/a>\r\n<\/div>    \r\n  <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n<\/div><\/article>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-item ui-ux-design web-development\">\r\n\t\t\t\t\t<div class=\"isotope-item-inner\">\r\n\t\t\t\t\t\t<article class=\"post-671 post type-post status-publish format-standard has-post-thumbnail hentry category-ui-ux-design category-web-development tag-development\">\r\n\t<!-- News Block -->\r\n<div class=\"blog-item-current-style1\">\r\n      <div class=\"entry-header\">\r\n      <div class=\"post-thumb lightgallery-lightbox\">\r\n\t\r\n\t<div class=\"post-thumb-inner\">\r\n\t\t<div class=\"thumb\">\r\n\t\t\t<img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-content\/uploads\/2022\/12\/bg14-672x448.jpg\" alt=\"10 Ways to achieve your business goal\"\/>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<\/div>    <\/div>\r\n    <div class=\"entry-content\">\r\n\r\n          \t<ul class=\"entry-meta list-inline\">\r\n\t\t\t\t<li class=\"list-inline-item author\"><i class=\"fa fa-user-circle-o\"><\/i> <span class=\"byline\">By <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/author\/admin\/\" rel=\"author\">admin<\/a><\/span><\/span><\/li>\r\n\t\t\t\t<li class=\"list-inline-item comments\"><i class=\"fa fa-comments-o\"><\/i> <a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/28\/10-ways-to-achieve-your-business-goal\/#comments\">1 Comment<\/a><\/li>\r\n\t\t<\/ul>\r\n\t    \r\n          <div class=\"title-holder\">\r\n        <h4 class=\"entry-title\"><a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/28\/10-ways-to-achieve-your-business-goal\/\" rel=\"bookmark\">10 Ways to achieve your business goal<\/a><\/h4>      <\/div>\r\n    \r\n          <div class=\"post-excerpt\">\r\n                  <div class=\"mascot-post-excerpt\">Duis aute irure dolor lipsum simply free text the local markets<\/div>              <\/div>\r\n    \r\n    \t\t\t<div class=\"btn-view-details post-btn-readmore \">\r\n    <a href=\"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/2023\/01\/28\/10-ways-to-achieve-your-business-goal\/\"\r\n      class=\"btn btn-plain-text-with-arrow-right\">\r\n      Read More    <\/a>\r\n<\/div>    \r\n  <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n<\/div><\/article>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<!-- end of the loop -->\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\r\n\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ab88be4 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"4ab88be4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-631588b7 tm-bg-color-over-image\" data-id=\"631588b7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5be86e50 elementor-section-boxed elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"5be86e50\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-671019c2 tm-bg-color-over-image\" data-id=\"671019c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e44791 elementor-widget elementor-widget-tm-ele-iconbox\" data-id=\"6e44791\" data-element_type=\"widget\" data-widget_type=\"tm-ele-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-icon-box icon-box icon-left tm-iconbox-icontype-font-icon icon-default icon-position-icon-left animate-icon-on-hover animate-icon-rotate-y\" >\r\n\t\r\n  \t<div class=\"icon-box-wrapper\">\r\n\t\t\r\n\t\t<div class=\"icon-wrapper\">\r\n\t\t<a class=\"icon icon-type-font-icon icon-size-default icon-default-bg icon-default\"\r\n\r\n\t\t\t\t\t\t\t\t\thref=\"tel:+12345678\"\r\n\t\t\t\t\t\t\t\t>\r\n\t\t\t<i aria-hidden=\"true\" class=\" flaticon-common-call\"><\/i>\t\t<\/a>\r\n\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"icon-text\">\r\n\t\t\t\t\t\t<div class=\"content\">Have any question?<\/div>\r\n\t\t\t\r\n\t\t\t\t<h5 class=\"icon-box-title \">\r\n\t\t\t\t\t\t\t(123) 456-7890\t\t\t\t\t<\/h5>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\r\n\t\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"clearfix\"><\/div>\r\n\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2f5ef967 tm-bg-color-over-image\" data-id=\"2f5ef967\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bae23cb elementor-widget elementor-widget-tm-ele-iconbox\" data-id=\"5bae23cb\" data-element_type=\"widget\" data-widget_type=\"tm-ele-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-icon-box icon-box icon-left tm-iconbox-icontype-font-icon icon-default icon-position-icon-left animate-icon-on-hover animate-icon-rotate-y\" >\r\n\t\r\n  \t<div class=\"icon-box-wrapper\">\r\n\t\t\r\n\t\t<div class=\"icon-wrapper\">\r\n\t\t<a class=\"icon icon-type-font-icon icon-size-default icon-default-bg icon-default\"\r\n\r\n\t\t\t\t\t\t\t\t\thref=\"mailto:info@yourdomain.com\"\r\n\t\t\t\t\t\t\t\t>\r\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t<\/a>\r\n\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"icon-text\">\r\n\t\t\t\t\t\t<div class=\"content\">Send email<\/div>\r\n\t\t\t\r\n\t\t\t\t<h5 class=\"icon-box-title \">\r\n\t\t\t\t\t\t\tinfo@yourdomain.com\t\t\t\t\t<\/h5>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\r\n\t\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"clearfix\"><\/div>\r\n\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-651621e8 tm-bg-color-over-image\" data-id=\"651621e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67a96788 elementor-widget elementor-widget-tm-ele-iconbox\" data-id=\"67a96788\" data-element_type=\"widget\" data-widget_type=\"tm-ele-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"tm-sc-icon-box icon-box icon-left tm-iconbox-icontype-font-icon icon-default icon-position-icon-left animate-icon-on-hover animate-icon-rotate-y\" >\r\n\t\r\n  \t<div class=\"icon-box-wrapper\">\r\n\t\t\r\n\t\t<div class=\"icon-wrapper\">\r\n\t\t<a class=\"icon icon-type-font-icon icon-size-default icon-default-bg icon-default\"\r\n\r\n\t\t\t\t\t\t\t\t\thref=\"#\"\r\n\t\t\t\t\t\t\t\t>\r\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t<\/a>\r\n\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"icon-text\">\r\n\t\t\t\t\t\t<div class=\"content\">Visit anytime<\/div>\r\n\t\t\t\r\n\t\t\t\t<h5 class=\"icon-box-title \">\r\n\t\t\t\t\t\t\tLorem Ipsum 123 ST, USA\t\t\t\t\t<\/h5>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\r\n\t\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"clearfix\"><\/div>\r\n\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6bf0be7e tm-bg-color-over-image\" data-id=\"6bf0be7e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52fcd9d4 elementor-widget elementor-widget-tm-ele-text-editor\" data-id=\"52fcd9d4\" data-element_type=\"widget\" data-widget_type=\"tm-ele-text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-text-editor\">\r\n\t\t<p>Follow us now<\/p>\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2687dfb elementor-widget elementor-widget-tm-ele-social-links\" data-id=\"2687dfb\" data-element_type=\"widget\" data-widget_type=\"tm-ele-social-links.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"tm-sc-social-links center icon-md links-outlined\">\r\n\r\n\t\t<li><a class=\"social-link\" href=\"#\" target=\"_self\"><i class=\"fa fa-twitter\"><\/i><\/a><\/li>\r\n\t\t\t<li><a class=\"social-link\" href=\"#\" target=\"_self\"><i class=\"fa fa-facebook\"><\/i><\/a><\/li>\r\n\t\t\r\n\t\t\t<li><a class=\"social-link\" href=\"#\" target=\"_self\"><i class=\"fa fa-instagram\"><\/i><\/a><\/li>\r\n\t\t\t\r\n\t\t\t<\/ul>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-525149c8 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default tm-col-stretched-none tm-bg-color-over-image\" data-id=\"525149c8\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ff6707 tm-bg-color-over-image\" data-id=\"6ff6707\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f24941d elementor-widget elementor-widget-google_maps\" data-id=\"f24941d\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=USA&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"USA\"\n\t\t\t\t\taria-label=\"USA\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Web &#038; App Solutions Web Design &#038; Development and App Making Contact Us ABOUT The Affordable Designs There are many&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-42933","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/pages\/42933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/comments?post=42933"}],"version-history":[{"count":28,"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/pages\/42933\/revisions"}],"predecessor-version":[{"id":47158,"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/pages\/42933\/revisions\/47158"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/media?parent=42933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}