{"id":17,"count":3,"description":"","link":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/category\/cloud-solution\/","name":"Cloud solution","slug":"cloud-solution","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/testv45.demowebsitelinks.com\/theaffordabledesigns\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}