{"id":15,"date":"2022-11-07T07:23:43","date_gmt":"2022-11-07T07:23:43","guid":{"rendered":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/my-account\/"},"modified":"2022-11-07T07:23:43","modified_gmt":"2022-11-07T07:23:43","slug":"my-account","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/my-account\/","title":{"rendered":"My account"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":0,"href":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/pottyfriend\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}