{"id":10,"date":"2023-08-09T13:27:56","date_gmt":"2023-08-09T13:27:56","guid":{"rendered":"https:\/\/testv45.demowebsitelinks.com\/moniz\/cart\/"},"modified":"2023-08-09T13:27:56","modified_gmt":"2023-08-09T13:27:56","slug":"cart","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/moniz\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/moniz\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/moniz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/moniz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/moniz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/moniz\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":0,"href":"https:\/\/testv45.demowebsitelinks.com\/moniz\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/moniz\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}