{"id":9,"date":"2022-07-18T05:54:30","date_gmt":"2022-07-18T05:54:30","guid":{"rendered":"https:\/\/testv17.demowebsitelinks.com\/sidikatavernier\/cart\/"},"modified":"2022-07-18T05:54:30","modified_gmt":"2022-07-18T05:54:30","slug":"cart","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":0,"href":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/lawrencespireksrv2\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}