{"id":7585,"date":"2022-03-16T12:45:49","date_gmt":"2022-03-16T12:45:49","guid":{"rendered":"https:\/\/rstheme.com\/products\/wordpress\/innovix\/cart\/"},"modified":"2022-03-16T12:45:49","modified_gmt":"2022-03-16T12:45:49","slug":"cart","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/innovix\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"<p>[woocommerce_cart]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7585","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/innovix\/wp-json\/wp\/v2\/pages\/7585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/innovix\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/innovix\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/innovix\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/innovix\/wp-json\/wp\/v2\/comments?post=7585"}],"version-history":[{"count":0,"href":"https:\/\/testv45.demowebsitelinks.com\/innovix\/wp-json\/wp\/v2\/pages\/7585\/revisions"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/innovix\/wp-json\/wp\/v2\/media?parent=7585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}