{"id":2136,"date":"2023-08-25T06:25:21","date_gmt":"2023-08-25T06:25:21","guid":{"rendered":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/?post_type=product&#038;p=2136"},"modified":"2023-08-28T15:24:05","modified_gmt":"2023-08-28T15:24:05","slug":"skirt-steak","status":"publish","type":"product","link":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/product\/skirt-steak\/","title":{"rendered":"Product"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2525,"comment_status":"open","ping_status":"closed","template":"","meta":{"_links_to":"","_links_to_target":""},"product_cat":[50],"product_tag":[39],"class_list":["post-2136","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-henry-ervins-bbq","product_tag-steakhouse-menu"],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/product\/2136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/comments?post=2136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/media\/2525"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/media?parent=2136"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/product_cat?post=2136"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/henryervinsBBQv2\/wp-json\/wp\/v2\/product_tag?post=2136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}