{"id":41,"count":5,"description":"","link":"https:\/\/testv45.demowebsitelinks.com\/agstrategies\/events\/category\/seminars\/","name":"Seminars","slug":"seminars","taxonomy":"tribe_events_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/agstrategies\/wp-json\/wp\/v2\/tribe_events_cat\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/agstrategies\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/agstrategies\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/testv45.demowebsitelinks.com\/agstrategies\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}