{"id":16,"count":1,"description":"","link":"https:\/\/testv45.demowebsitelinks.com\/WynTech\/category\/broadband\/","name":"Broadband","slug":"broadband","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/WynTech\/wp-json\/wp\/v2\/categories\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/WynTech\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/WynTech\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/testv45.demowebsitelinks.com\/WynTech\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}