{"id":10177,"date":"2023-08-30T14:57:02","date_gmt":"2023-08-30T14:57:02","guid":{"rendered":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/?page_id=10177"},"modified":"2023-10-19T13:24:11","modified_gmt":"2023-10-19T13:24:11","slug":"healthcare-in-zambia","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/healthcare-in-zambia\/","title":{"rendered":"Healthcare In Zambia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10177\" class=\"elementor elementor-10177\">\n\t\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-798c50d wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"798c50d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e442bef\" data-id=\"e442bef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a61584 elementor-widget elementor-widget-page-title\" data-id=\"5a61584\" data-element_type=\"widget\" data-settings=\"{&quot;align&quot;:&quot;center&quot;}\" data-widget_type=\"page-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"hfe-page-title hfe-page-title-wrapper elementor-widget-heading\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\">\n\t\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\n\t\t\t\t\t\t\t\t\n\t\t\t\tHealthcare In Zambia  \n\t\t\t<\/h2 > \n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-1d4f1ae elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"1d4f1ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1c6079\" data-id=\"f1c6079\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-cee8765 wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cee8765\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-480d245 wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"480d245\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a94fd9 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"7a94fd9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<blockquote data-animation-role=\"quote\">\u201cCongratulations VDr. You are an inspiration for the Clinicians in the country!<br \/>We Thank God for the service.\u201d<\/blockquote><p>\u2014 VDRs service user Victor Mulenga<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-b92198a wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b92198a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7ddce92 wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"7ddce92\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69275dd elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"69275dd\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1151\" height=\"744\" src=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1.jpg\" class=\"attachment-full size-full wp-image-10188\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1.jpg 1151w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1-400x259.jpg 400w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1-768x496.jpg 768w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1-860x556.jpg 860w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1-430x278.jpg 430w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1-700x452.jpg 700w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_5351-1-150x97.jpg 150w\" sizes=\"auto, (max-width: 1151px) 100vw, 1151px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Too few doctors<\/h3><p class=\"elementor-image-box-description\">There are far too few doctors in Zambia \u2013 only 1 doctor for every 12,000 patients!<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-572b89c wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"572b89c\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ecc0ac elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8ecc0ac\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1070\" height=\"719\" src=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset.jpeg\" class=\"attachment-full size-full wp-image-10187\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset.jpeg 1070w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-400x269.jpeg 400w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-768x516.jpeg 768w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-860x578.jpeg 860w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-430x289.jpeg 430w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-700x470.jpeg 700w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-150x101.jpeg 150w\" sizes=\"auto, (max-width: 1070px) 100vw, 1070px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Doctors covering large  catchment areas<\/h3><p class=\"elementor-image-box-description\">2\/3 of doctors live in urban areas; 2\/3 of the population live in rural Zambia.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-171d198 wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"171d198\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ca7f56 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6ca7f56\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"752\" height=\"483\" src=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_4921.jpg\" class=\"attachment-full size-full wp-image-10186\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_4921.jpg 752w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_4921-400x257.jpg 400w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_4921-430x276.jpg 430w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_4921-700x450.jpg 700w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/IMG_4921-150x96.jpg 150w\" sizes=\"auto, (max-width: 752px) 100vw, 752px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Under-equipped rural health centres <\/h3><p class=\"elementor-image-box-description\">Consequently, most rural health centres are under-staffed and under-equipped.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-dfcd93b wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfcd93b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1643876 wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"1643876\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec256e4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ec256e4\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/PatientatMakeni.jpg\" class=\"attachment-full size-full wp-image-10191\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/PatientatMakeni.jpg 800w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/PatientatMakeni-400x267.jpg 400w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/PatientatMakeni-768x512.jpg 768w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/PatientatMakeni-430x286.jpg 430w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/PatientatMakeni-700x466.jpg 700w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/PatientatMakeni-150x100.jpg 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Health workers challenged  <\/h3><p class=\"elementor-image-box-description\">Health workers struggle to diagnose and treat many chronic and acute conditions, so patient conditions can deteriorate. <\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4bd7056 wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"4bd7056\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65e0678 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"65e0678\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-1.jpeg\" class=\"attachment-full size-full wp-image-10192\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-1.jpeg 800w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-1-400x267.jpeg 400w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-1-768x513.jpeg 768w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-1-430x287.jpeg 430w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-1-700x467.jpeg 700w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/08\/image-asset-1-150x100.jpeg 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Distant referrals<\/h3><p class=\"elementor-image-box-description\">Patients may have to walk or cycle for many hours, or even days, to reach a district hospital. Costs of transport are prohibitive to many.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-117fce7 wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"117fce7\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25fb8bb elementor-widget elementor-widget-heading\" data-id=\"25fb8bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Health Stats:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4995d0a color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"4995d0a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h4>1 in 14 (64 \u00a0children per 1000) children will not reach the age of 5*<\/h4>\n<h3>11.1 [10.5 &#8211; 11.6] of the adult population are HIV+*<\/h3>\n<p class=\"\"><em>\u00a0* UNICEF The State of the World\u2019s Children report, 2019<\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81e69c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"81e69c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-26ff4dd\" data-id=\"26ff4dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa1237c wd-animation-slide-from-left wd-animation-slow elementor-invisible\" data-id=\"aa1237c\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ded03 elementor-widget elementor-widget-google_maps\" data-id=\"77ded03\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=zambia&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"zambia\"\n\t\t\t\t\taria-label=\"zambia\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c882135\" data-id=\"c882135\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e5ecd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"7e5ecd6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b52de8\" data-id=\"2b52de8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9627f18 elementor-widget elementor-widget-heading\" data-id=\"9627f18\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Telemedicine helps solve these problems<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-972461b color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"972461b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"\">The Zambian Ministry of Health&#8217;s e-Health Strategy 2017-21 included telemedicine in its strategic priorities. It accepted the \u201cneed to embrace and promote telemedicine\u2026 by developing a comprehensive framework, guidelines and operational model on its use.\u201d\u00a0<\/p><p class=\"\">There is also growing academic research into telemedicine. Salatian<em> et al<\/em> (1) note &#8216;benefits at federal, state and community level&#8230;across all political parties, religious dogmas, village councils and tribal and ethnic groups.&#8221;<\/p><p class=\"\">Research to prove the value of telemedicine to healthcare workers in rural Kenya compared face to face consultations with submitted telemedicine case files for the same sample of patients. Medical feedback was consistent between the two methods in 78% of cases; and treatment advice was consistent between the two methods in 89% of cases (2).\u00a0\u00a0\u00a0\u00a0<\/p><p class=\"\">1.\u00a0Salatian, A., Zivkovic, J. and Ademoh, F. (2012) <em>Telemedicine for Rural Sub-Saharan Africa &#8211; Benefits and Drawbacks.<\/em> Allied Academies International Conference, Academy of Health Care Management 9(1), pp. 9-13<\/p><p class=\"\">2.\u00a0Qin, R., Dzombak, R., Amin, R. and Mehta, K. (2013) <em>Reliability of a Telemedicine System Designed for Rural Kenya. <\/em>Journal of Primary Care &amp; Community Health, Vol. 4, No. 3, pp. 177- 181<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4029b8e elementor-widget elementor-widget-heading\" data-id=\"4029b8e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Latest figures <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b88ec7 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"2b88ec7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Over 290 users trained across all provinces and 42 districts in Zambia.<\/p><p>231 volunteer Doctors responding to cases covering multiple specialities.<\/p><p>The majority of our volunteers have experience working in resource poor settings so have an understanding of the issues the Clinical Officers face. The feedback from the Clinical Officers confirmed that the Virtual Doctors advice was beneficial.<\/p><p>90% said it helped improve patient symptoms<\/p><p>76% said it prevented a referral to hospital 94% found it educational Their comments included:<\/p><p><em>\u201cAm learning a lot from the doctors in the UK. I appreciate the work they are doing. Work becomes much easy. \u201c<\/em><\/p><p><em>\u201cVDrs very helpful. As the programme does not only benefit the patients but also increases knowledge for the healthy provider. Keep it up VDrs\u201d<\/em><\/p><p><em>\u201cThe Information is very educational. Timing is good. Less than 24 hrs you have the answers.\u201d<\/em><\/p><p><em>\u201cThe interaction with the Doctor helped me manage the case better. Thankful very much for the advice from the Doctor.\u201d<br \/><\/em>It costs approximately $2,500 to set up and train a Clinical Officer and provide equipment and bandwidth to access the service for 12 months.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b03db1 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"5b03db1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/donate-today\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Donate Now<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06fef89 wd-section-stretch elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06fef89\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-541edf9\" data-id=\"541edf9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7cc5ad elementor-widget elementor-widget-wd_title\" data-id=\"a7cc5ad\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-primary subtitle-style-background wd-fontsize-xs\">\n\t\t\t\t\tSalem Bible College &amp; Seminary\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxl\">Why Choose Us<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0331bfe color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"0331bfe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Lorem Ipsum<\/strong>\u00a0is simply dummy text of the printing and typesetting industry. Lorem Ipsum has been the industry&#8217;s standard dummy text ever since the 1500s, when an unknown printer took a galley of type and scrambled it to make a type specimen book. It has survived not only five centuries, but also the leap into electronic typesetting, remaining essentially unchanged.<\/p><p>It was popularised in the 1960s with the release of Letraset sheets containing Lorem Ipsum passages, and more recently with desktop publishing software like Aldus PageMaker including versions of Lorem Ipsum.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-701fdfa color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"701fdfa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tIt is a long established fact that a reader will be distracted by the readable content of a page when looking at its layout. The point of using Lorem Ipsum is that it has a more-or-less normal distribution of letters, as opposed to using &#8216;Content here, content here&#8217;, making it look like readable English.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-03239b1\" data-id=\"03239b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98912d3 elementor-widget elementor-widget-image\" data-id=\"98912d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/04\/ph2.jpg\" class=\"attachment-large size-large wp-image-9229\" alt=\"\" srcset=\"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/04\/ph2.jpg 600w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/04\/ph2-300x300.jpg 300w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/04\/ph2-150x150.jpg 150w, https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-content\/uploads\/2023\/04\/ph2-430x430.jpg 430w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Healthcare In Zambia \u201cCongratulations VDr. You are an inspiration for the Clinicians in the country!We Thank God for the service.\u201d<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-10177","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/pages\/10177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/comments?post=10177"}],"version-history":[{"count":28,"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/pages\/10177\/revisions"}],"predecessor-version":[{"id":11349,"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/pages\/10177\/revisions\/11349"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/VirtualDoctorsUSA\/wp-json\/wp\/v2\/media?parent=10177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}