{"id":12,"date":"2022-03-21T05:54:26","date_gmt":"2022-03-21T05:54:26","guid":{"rendered":"https:\/\/testv40.demowebsitelinks.com\/phenomenal\/cart\/"},"modified":"2022-03-21T05:54:26","modified_gmt":"2022-03-21T05:54:26","slug":"cart","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":0,"href":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/TheClubHouse\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}