{"id":11,"date":"2023-07-17T05:01:35","date_gmt":"2023-07-17T05:01:35","guid":{"rendered":"http:\/\/noxiy.local\/?page_id=8"},"modified":"2023-08-24T05:52:55","modified_gmt":"2023-08-24T05:52:55","slug":"home-01-light","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/home-01-light\/","title":{"rendered":"Home 01 &#8211; Light"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11\" class=\"elementor elementor-11\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0fabb2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fabb2f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-775ff38\" data-id=\"775ff38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad718a5 elementor-widget__width-auto elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ad718a5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Insurance Agency <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09333ae elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"09333ae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Invest in Your Health<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d9e365 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d9e365\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d832c6\" data-id=\"1d832c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cc4dbc elementor-widget elementor-widget-button-noxiy\" data-id=\"3cc4dbc\" data-element_type=\"widget\" data-widget_type=\"button-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"noxiy-button\">\r\n            <a href=\"\/services-01\" class=\"noxiy__btn\">\r\n                Our Seervices            <\/a>\r\n\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33dbfd9\" data-id=\"33dbfd9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c290e6 elementor-widget__width-initial elementor-widget elementor-widget-image-noxiy\" data-id=\"6c290e6\" data-element_type=\"widget\" data-widget_type=\"image-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n        \r\n\r\n        \r\n        \r\n         \r\n        \r\n        \r\n        \r\n            <div class=\"banner__four-content-button-customer\">\r\n                <div>                        \r\n                    <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/banner-avater.png\" alt=\"No alt text\" \/>                <\/div>\r\n                <div>\r\n                    <h6><i class=\"fa fa-star\"><\/i> <span class=\"counter\">\r\n                            500                        <\/span>\r\n                        +                    <\/h6>\r\n                    <h5>\r\n                        Customers                    <\/h5>\r\n                <\/div>\r\n            <\/div>\r\n\r\n          \r\n        \r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8da3d2d elementor-hidden-mobile\" data-id=\"8da3d2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c61c0d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5c61c0d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-875be61\" data-id=\"875be61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9777b41 elementor-widget elementor-widget-text-slide-noxiy\" data-id=\"9777b41\" data-element_type=\"widget\" data-widget_type=\"text-slide-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n\r\n        <!-- Text Slider Area Start -->\r\n        <div class=\"text__slider two\">\r\n            <div class=\"text-slide\">\r\n                <div class=\"sliders scroll\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/family-insurance\">Family Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/home-insurance\">  Home Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/travel-insurance\">    Travel Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/disability-insurance\">Disability Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/car-insurance\">  Car Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n                <div class=\"sliders scroll\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/family-insurance\">Family Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/home-insurance\">  Home Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/travel-insurance\">    Travel Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/disability-insurance\">Disability Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <h2><a href=\"\/portfolio\/car-insurance\">  Car Insurance<\/a><span\r\n                                        class=\"fa fa-star\"><\/span><\/h2>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <!-- Text Slider Area Start -->\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07cc979 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07cc979\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-adf2767\" data-id=\"adf2767\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac22e1 elementor-widget elementor-widget-image-noxiy\" data-id=\"8ac22e1\" data-element_type=\"widget\" data-widget_type=\"image-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        \r\n            <div class=\"about__five-left\">\r\n                <img decoding=\"async\" class=\"about__five-left-shape\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/about-5.png\" alt=\"No alt text\" \/>                <div class=\"about__five-left-image\">\r\n                    <div class=\"about__five-left-image-left image-overlay\">\r\n                        <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/about-10.jpg\" alt=\"No alt text\" \/>                    <\/div>\r\n                    <div class=\"about__five-left-image-right\">\r\n                        <div class=\"image-overlay\">\r\n                            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/about-11.jpg\" alt=\"No alt text\" \/>                        <\/div>\r\n                        <div class=\"image-overlay\">\r\n                            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/about-12.jpg\" alt=\"No alt text\" \/>                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"about__five-left-image-experience\">\r\n                        <h1><span class=\"counter\">\r\n                                31                            <\/span>+                        <\/h1>\r\n                        <h6>\r\n                            Years Experience Our Company                        <\/h6>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n        \r\n\r\n        \r\n        \r\n         \r\n        \r\n        \r\n          \r\n        \r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8aa9968\" data-id=\"8aa9968\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77fab89 elementor-widget elementor-widget-subtitle-noxiy\" data-id=\"77fab89\" data-element_type=\"widget\" data-widget_type=\"subtitle-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        <div class=\"subtitle-noxiy\">\r\n            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/subtitle-1.png\" alt=\"No alt text\" \/>            <span>\r\n                 Company Overview             <\/span>\r\n        <\/div>\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-964d9f4 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"964d9f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trusted Partner for Health Coverage<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf3f9ff elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"cf3f9ff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Insurance brokers can help you find health coverage that meets your specific needs and budget. They work with multiple insurance companies and can provide you with.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-432bdd6 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"432bdd6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a7334c3\" data-id=\"a7334c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecdc12e elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"ecdc12e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"120\" src=\"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-content\/uploads\/2023\/07\/avatar-13.jpg\" class=\"attachment-full size-full wp-image-725\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9658d55\" data-id=\"9658d55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf6397f elementor-widget elementor-widget-heading\" data-id=\"bf6397f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">David Beckham<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b907085 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"b907085\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\"> Founder CEO <\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f7507e elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"0f7507e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Get peace of mind by choosing the best insurance provider for you.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb009c elementor-widget elementor-widget-button-noxiy\" data-id=\"9fb009c\" data-element_type=\"widget\" data-widget_type=\"button-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"noxiy-button\">\r\n            <a href=\"\/about-us\" class=\"noxiy__btn\">\r\n                 Discover More             <\/a>\r\n\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26f0274 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26f0274\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99d72d9\" data-id=\"99d72d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45ff657 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"45ff657\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d5dd052\" data-id=\"d5dd052\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b72a6b elementor-widget elementor-widget-counter-noxiy\" data-id=\"6b72a6b\" data-element_type=\"widget\" data-widget_type=\"counter-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"counter__two-item\">\r\n                <div class=\"counter__two-item-icon\">\r\n\t\t\t\t\t<i class=\"flaticon flaticon-team\"><\/i>\r\n                <\/div>\r\n                <div class=\"counter__two-item-content\">\r\n                    <h2>\r\n                        <span class=\"counter\">\r\n                            43                        <\/span>\r\n                        +                    <\/h2>\r\n                    <h6>\r\n                        Expert Team                    <\/h6>\r\n                <\/div>\r\n            <\/div>\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-83925ee\" data-id=\"83925ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef70edc elementor-widget elementor-widget-counter-noxiy\" data-id=\"ef70edc\" data-element_type=\"widget\" data-widget_type=\"counter-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"counter__two-item\">\r\n                <div class=\"counter__two-item-icon\">\r\n\t\t\t\t\t<i class=\"flaticon flaticon-success\"><\/i>\r\n                <\/div>\r\n                <div class=\"counter__two-item-content\">\r\n                    <h2>\r\n                        <span class=\"counter\">\r\n                            27                        <\/span>\r\n                        +                    <\/h2>\r\n                    <h6>\r\n                        National Award                    <\/h6>\r\n                <\/div>\r\n            <\/div>\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-aba6d11\" data-id=\"aba6d11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd32fa9 elementor-widget elementor-widget-counter-noxiy\" data-id=\"bd32fa9\" data-element_type=\"widget\" data-widget_type=\"counter-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"counter__two-item\">\r\n                <div class=\"counter__two-item-icon\">\r\n\t\t\t\t\t<i class=\"flaticon flaticon-project-management\"><\/i>\r\n                <\/div>\r\n                <div class=\"counter__two-item-content\">\r\n                    <h2>\r\n                        <span class=\"counter\">\r\n                            192                        <\/span>\r\n                        +                    <\/h2>\r\n                    <h6>\r\n                        Project Completed                    <\/h6>\r\n                <\/div>\r\n            <\/div>\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1fc1e80\" data-id=\"1fc1e80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f54b91a elementor-widget elementor-widget-counter-noxiy\" data-id=\"f54b91a\" data-element_type=\"widget\" data-widget_type=\"counter-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"counter__two-item\">\r\n                <div class=\"counter__two-item-icon\">\r\n\t\t\t\t\t<i class=\"flaticon flaticon-costumer\"><\/i>\r\n                <\/div>\r\n                <div class=\"counter__two-item-content\">\r\n                    <h2>\r\n                        <span class=\"counter\">\r\n                            187                        <\/span>\r\n                        +                    <\/h2>\r\n                    <h6>\r\n                        Happy Client                    <\/h6>\r\n                <\/div>\r\n            <\/div>\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bf3916 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bf3916\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8df1eb4\" data-id=\"8df1eb4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c35145a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c35145a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e9fdf54\" data-id=\"e9fdf54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15d90c7 elementor-widget elementor-widget-subtitle-noxiy\" data-id=\"15d90c7\" data-element_type=\"widget\" data-widget_type=\"subtitle-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        <div class=\"subtitle-noxiy\">\r\n            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/subtitle-1.png\" alt=\"No alt text\" \/>            <span>\r\n                Available Insurance            <\/span>\r\n        <\/div>\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5de2b34 elementor-widget elementor-widget-heading\" data-id=\"5de2b34\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We Provide Best Insurance<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46ecc51 elementor-widget elementor-widget-services_noxiy\" data-id=\"46ecc51\" data-element_type=\"widget\" data-widget_type=\"services_noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n                                    <div class=\"services__four-item\">\r\n                    <div class=\"services__four-item-left\">\r\n                        <i class=\"flaticon flaticon-medical-report\"><\/i>\r\n                        <h3><a href=\"\/service\/medical-insurance\">Medical Insurance<\/a><\/h3>\r\n                        <p>\r\n                            Medical insurance plans can be purchased through private insurance companies or through government programs, such as Medicare or Medicaid. These plans typically require.                        <\/p>\r\n                    <\/div>\r\n                    <div class=\"services__four-item-right\">\r\n                        <a href=\"\/service\/medical-insurance\"><i class=\"flaticon-right-up\"><\/i><\/a>\r\n                    <\/div>\r\n                <\/div>\r\n                            <div class=\"services__four-item\">\r\n                    <div class=\"services__four-item-left\">\r\n                        <i class=\"flaticon flaticon-social\"><\/i>\r\n                        <h3><a href=\"\/service\/disability-insurance\">Disability Insurance<\/a><\/h3>\r\n                        <p>\r\n                            Disability insurance policies typically require individuals to pay monthly premiums in exchange for coverage. The amount of coverage provided by a disability insurance policy.                        <\/p>\r\n                    <\/div>\r\n                    <div class=\"services__four-item-right\">\r\n                        <a href=\"\/service\/disability-insurance\"><i class=\"flaticon-right-up\"><\/i><\/a>\r\n                    <\/div>\r\n                <\/div>\r\n                            <div class=\"services__four-item\">\r\n                    <div class=\"services__four-item-left\">\r\n                        <i class=\"flaticon flaticon-dental-insurance\"><\/i>\r\n                        <h3><a href=\"\/service\/dental-insurance\"> Dental Insurance<\/a><\/h3>\r\n                        <p>\r\n                            Dental insurance covers dental care, including preventive and extensive procedures, and requires monthly premiums with possible co-payments or deductibles.                        <\/p>\r\n                    <\/div>\r\n                    <div class=\"services__four-item-right\">\r\n                        <a href=\"\/service\/dental-insurance\"><i class=\"flaticon-right-up\"><\/i><\/a>\r\n                    <\/div>\r\n                <\/div>\r\n                    \r\n        \r\n\r\n        \r\n        \r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2244c61 elementor-widget elementor-widget-text-editor\" data-id=\"2244c61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"services__four-titles\">\n\t\t\t\t\t\t\t<span>Discover the Benefits of Choosing Our Health Insurance Services Today <a href=\"\/request-quote\">Request Quote<\/a><\/span>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8a6f6a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8a6f6a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-902a8db\" data-id=\"902a8db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43ca57c elementor-widget elementor-widget-subtitle-noxiy\" data-id=\"43ca57c\" data-element_type=\"widget\" data-widget_type=\"subtitle-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        <div class=\"subtitle-noxiy\">\r\n            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/subtitle-1.png\" alt=\"No alt text\" \/>            <span>\r\n                Who We Are            <\/span>\r\n        <\/div>\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-084ecd9 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"084ecd9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Your Health and Wellness, Our Priority<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f368b1f elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"f368b1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Regular exercise can help maintain a healthy weight, reduce the risk of chronic diseases, improve mood, and increase energy levels. Eating a balanced diet that includes a variety of fruits, vegetables.\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9fa0ff elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a9fa0ff\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Get Matched to Your Ideal Plan<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quality Health Insurance and Care<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee6357f elementor-widget elementor-widget-button-noxiy\" data-id=\"ee6357f\" data-element_type=\"widget\" data-widget_type=\"button-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"noxiy-button\">\r\n            <a href=\"\/about-us\" class=\"noxiy__btn\">\r\n                 Read More             <\/a>\r\n\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d41446\" data-id=\"7d41446\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-322ff94 elementor-widget elementor-widget-image-noxiy\" data-id=\"322ff94\" data-element_type=\"widget\" data-widget_type=\"image-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        \r\n\r\n        \r\n            <div class=\"who__area-right\">\r\n                <div class=\"who__area-right-image t-right\">\r\n                    <img decoding=\"async\" class=\"who__area-right-image-shape\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/who.png\" alt=\"No alt text\" \/>\r\n                    <img decoding=\"async\" class=\"who__area-right-image-shape-one left-right-animate\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/who-1.png\" alt=\"No alt text\" \/>\r\n                    <div class=\"image-overlay dark__image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/who-1.jpg\" alt=\"No alt text\" \/>                    <\/div>\r\n                    <div class=\"image-overlay dark__image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/who-2.jpg\" alt=\"No alt text\" \/>                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n        \r\n\r\n        \r\n        \r\n         \r\n        \r\n        \r\n          \r\n        \r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ec60aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ec60aa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30cf2e4\" data-id=\"30cf2e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f00e401 elementor-widget elementor-widget-subtitle-noxiy\" data-id=\"f00e401\" data-element_type=\"widget\" data-widget_type=\"subtitle-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        <div class=\"subtitle-noxiy\">\r\n            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/subtitle-1.png\" alt=\"No alt text\" \/>            <span>\r\n                Our Team Member            <\/span>\r\n        <\/div>\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9198525 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9198525\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Specialist<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-368f21e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"368f21e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-947b279\" data-id=\"947b279\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc450c elementor-widget elementor-widget-team-noxiy\" data-id=\"cbc450c\" data-element_type=\"widget\" data-widget_type=\"team-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        \r\n            <div class=\"team__six-item\">\r\n\t\t\t\t<div class=\"team__six-item-image\">\r\n                    <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/team-4-1.jpg\" alt=\"No alt text\" \/>\t\t\t\t\t<div class=\"team__two-item-image-icon four\">\r\n                                                    <div class=\"team__two-item-image-social\">\r\n                                <ul>\r\n                                                                            <li><a href=\"https:\/\/facebook.com\"><i\r\n                                        class=\"fab fa-facebook-f\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"https:\/\/twitter.com\"><i\r\n                                        class=\"fab fa-twitter\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"https:\/\/behance.com\"><i\r\n                                        class=\"fab fa-behance\"><\/i><\/a><\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n\t\t\t\t\t\t\t<span><i class=\"fas fa-share-alt\"><\/i><\/span>\r\n                                            <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"team__six-item-content\">\r\n\t\t\t\t\t<span>Senior Advisor<\/span>\r\n\t\t\t\t\t                        <h4><a href=\"\/amelia-clover\">Amelia Clover<\/a><\/h4>\r\n                    \t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n        \r\n        \r\n        \r\n                \r\n                \r\n        \r\n\r\n\r\n\r\n\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8447d86\" data-id=\"8447d86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06c3a90 elementor-widget elementor-widget-team-noxiy\" data-id=\"06c3a90\" data-element_type=\"widget\" data-widget_type=\"team-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        \r\n            <div class=\"team__six-item\">\r\n\t\t\t\t<div class=\"team__six-item-image\">\r\n                    <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/team-2-2.jpg\" alt=\"No alt text\" \/>\t\t\t\t\t<div class=\"team__two-item-image-icon four\">\r\n                                                    <div class=\"team__two-item-image-social\">\r\n                                <ul>\r\n                                                                            <li><a href=\"http:\/\/facebook.com\"><i\r\n                                        class=\"fab fa-facebook-f\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"http:\/\/twitter.com\"><i\r\n                                        class=\"fab fa-twitter\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"http:\/\/behance.com\"><i\r\n                                        class=\"fab fa-behance\"><\/i><\/a><\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n\t\t\t\t\t\t\t<span><i class=\"fas fa-share-alt\"><\/i><\/span>\r\n                                            <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"team__six-item-content\">\r\n\t\t\t\t\t<span>Health Coach<\/span>\r\n\t\t\t\t\t                        <h4><a href=\"\/steve-rhodes\">Steve Rhodes<\/a><\/h4>\r\n                    \t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n        \r\n        \r\n        \r\n                \r\n                \r\n        \r\n\r\n\r\n\r\n\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3eba2aa\" data-id=\"3eba2aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b121ab8 elementor-widget elementor-widget-team-noxiy\" data-id=\"b121ab8\" data-element_type=\"widget\" data-widget_type=\"team-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        \r\n            <div class=\"team__six-item\">\r\n\t\t\t\t<div class=\"team__six-item-image\">\r\n                    <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/team-8-1.jpg\" alt=\"No alt text\" \/>\t\t\t\t\t<div class=\"team__two-item-image-icon four\">\r\n                                                    <div class=\"team__two-item-image-social\">\r\n                                <ul>\r\n                                                                            <li><a href=\"http:\/\/facebook.com\"><i\r\n                                        class=\"fab fa-facebook-f\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"http:\/\/twitter.com\"><i\r\n                                        class=\"fab fa-twitter\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"http:\/\/behance.com\"><i\r\n                                        class=\"fab fa-behance\"><\/i><\/a><\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n\t\t\t\t\t\t\t<span><i class=\"fas fa-share-alt\"><\/i><\/span>\r\n                                            <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"team__six-item-content\">\r\n\t\t\t\t\t<span>Underwriter<\/span>\r\n\t\t\t\t\t                        <h4><a href=\"\/grace-elizabeth\">Grace Elizabeth<\/a><\/h4>\r\n                    \t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n        \r\n        \r\n        \r\n                \r\n                \r\n        \r\n\r\n\r\n\r\n\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f6df5dc\" data-id=\"f6df5dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8120000 elementor-widget elementor-widget-team-noxiy\" data-id=\"8120000\" data-element_type=\"widget\" data-widget_type=\"team-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        \r\n            <div class=\"team__six-item\">\r\n\t\t\t\t<div class=\"team__six-item-image\">\r\n                    <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/team-5-1.jpg\" alt=\"No alt text\" \/>\t\t\t\t\t<div class=\"team__two-item-image-icon four\">\r\n                                                    <div class=\"team__two-item-image-social\">\r\n                                <ul>\r\n                                                                            <li><a href=\"http:\/\/facebook.com\"><i\r\n                                        class=\"fab fa-facebook-f\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"http:\/\/twitter.com\"><i\r\n                                        class=\"fab fa-twitter\"><\/i><\/a><\/li>\r\n                                                                            <li><a href=\"http:\/\/behance.com\"><i\r\n                                        class=\"fab fa-behance\"><\/i><\/a><\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n\t\t\t\t\t\t\t<span><i class=\"fas fa-share-alt\"><\/i><\/span>\r\n                                            <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"team__six-item-content\">\r\n\t\t\t\t\t<span>Claims Adjuster<\/span>\r\n\t\t\t\t\t                        <h4><a href=\"\/michael-james\">Michael James<\/a><\/h4>\r\n                    \t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n        \r\n        \r\n        \r\n                \r\n                \r\n        \r\n\r\n\r\n\r\n\r\n\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9e86fd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e9e86fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e66242c\" data-id=\"e66242c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-681e5bb elementor-widget elementor-widget-portfolio_noxiy\" data-id=\"681e5bb\" data-element_type=\"widget\" data-widget_type=\"portfolio_noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        \r\n            <!-- Portfolio Area Start -->\r\n            <div class=\"portfolio__four dark__image\">\r\n                                    <div class=\"portfolio__four-item  \">\r\n                        <div class=\"portfolio__four-item-image\" data-background=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/wellness-program.jpg\"><\/div>\r\n                        <div class=\"portfolio__four-item-inner\">\r\n                            <div class=\"portfolio__four-item-inner-content\">\r\n                                <div class=\"portfolio__four-item-inner-content-top\">\r\n                                    <span>\r\n                                        01                                    <\/span>\r\n                                    <i class=\"flaticon flaticon-mental-health\"><\/i>\r\n                                    <h4><a href=\"\/portfolio\/wellness-program\">Wellness Program<\/a>\r\n                                    <\/h4>\r\n                                    <p>\r\n                                        Our Wellness Program offers comprehensive wellness assessments and screenings to help patients identify areas of improvement,                                    <\/p>\r\n                                <\/div>\r\n                                <div class=\"portfolio__four-item-inner-content-btn\">\r\n                                    <h4>\r\n                                        Wellness Program                                    <\/h4>\r\n                                    <span><a href=\"\/portfolio\/wellness-program\">Read More<\/a><\/span>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"portfolio__four-item active \">\r\n                        <div class=\"portfolio__four-item-image\" data-background=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/specialty-care.jpg\"><\/div>\r\n                        <div class=\"portfolio__four-item-inner\">\r\n                            <div class=\"portfolio__four-item-inner-content\">\r\n                                <div class=\"portfolio__four-item-inner-content-top\">\r\n                                    <span>\r\n                                        02                                    <\/span>\r\n                                    <i class=\"flaticon flaticon-healthcare-1\"><\/i>\r\n                                    <h4><a href=\"\/portfolio\/specialty-care\">Specialty Care<\/a>\r\n                                    <\/h4>\r\n                                    <p>\r\n                                        Our Specialty Care program provides access to top medical specialists and centers, ensuring that patients receive the highest quality,                                    <\/p>\r\n                                <\/div>\r\n                                <div class=\"portfolio__four-item-inner-content-btn\">\r\n                                    <h4>\r\n                                        Specialty Care                                    <\/h4>\r\n                                    <span><a href=\"\/portfolio\/specialty-care\">Read More<\/a><\/span>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"portfolio__four-item  \">\r\n                        <div class=\"portfolio__four-item-image\" data-background=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/digital-health.jpg\"><\/div>\r\n                        <div class=\"portfolio__four-item-inner\">\r\n                            <div class=\"portfolio__four-item-inner-content\">\r\n                                <div class=\"portfolio__four-item-inner-content-top\">\r\n                                    <span>\r\n                                        03                                    <\/span>\r\n                                    <i class=\"flaticon flaticon-medical-records\"><\/i>\r\n                                    <h4><a href=\"\/portfolio\/digital-health\">Digital Health<\/a>\r\n                                    <\/h4>\r\n                                    <p>\r\n                                        Our Digital Health program provides convenient and secure virtual visits, allowing patients to receive care from the comfort of their,                                    <\/p>\r\n                                <\/div>\r\n                                <div class=\"portfolio__four-item-inner-content-btn\">\r\n                                    <h4>\r\n                                        Digital Health                                    <\/h4>\r\n                                    <span><a href=\"\/portfolio\/digital-health\">Read More<\/a><\/span>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                    <div class=\"portfolio__four-item  \">\r\n                        <div class=\"portfolio__four-item-image\" data-background=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/cost-containment.jpg\"><\/div>\r\n                        <div class=\"portfolio__four-item-inner\">\r\n                            <div class=\"portfolio__four-item-inner-content\">\r\n                                <div class=\"portfolio__four-item-inner-content-top\">\r\n                                    <span>\r\n                                        04                                    <\/span>\r\n                                    <i class=\"flaticon flaticon-cost-saving\"><\/i>\r\n                                    <h4><a href=\"\/portfolio\/cost-containment\">Cost Containment<\/a>\r\n                                    <\/h4>\r\n                                    <p>\r\n                                        Our Cost Containment program provides transparent pricing and cost estimates, helping patients make informed healthcare decisions,                                    <\/p>\r\n                                <\/div>\r\n                                <div class=\"portfolio__four-item-inner-content-btn\">\r\n                                    <h4>\r\n                                        Cost Containment                                    <\/h4>\r\n                                    <span><a href=\"\/portfolio\/cost-containment\">Read More<\/a><\/span>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n            <!-- Portfolio Area End -->\r\n\r\n        \r\n        \r\n        \r\n    \r\n    \r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-383338b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"383338b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9494112\" data-id=\"9494112\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b47b923 elementor-widget elementor-widget-image-noxiy\" data-id=\"b47b923\" data-element_type=\"widget\" data-widget_type=\"image-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n            <div class=\"benefits__two-left\">\r\n\t\t\t\t<div class=\"benefits__two-left-image\">\r\n                    <img decoding=\"async\" class=\"benefits__two-left-image-shape\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/benefits.png\" alt=\"No alt text\" \/>\t\t\t\t\t<div class=\"image-overlay dark__image\">\r\n                        <img decoding=\"async\" class=\"benefits__two-left-image-one\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/benefits-2.jpg\" alt=\"No alt text\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"benefits__two-left-image-two image-overlay dark__image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/benefits-3.jpg\" alt=\"No alt text\" \/>\t\t\t\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n        \r\n\r\n        \r\n\r\n        \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n        \r\n\r\n        \r\n        \r\n         \r\n        \r\n        \r\n          \r\n        \r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e3fa4d\" data-id=\"4e3fa4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8b6126 elementor-widget elementor-widget-subtitle-noxiy\" data-id=\"c8b6126\" data-element_type=\"widget\" data-widget_type=\"subtitle-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        <div class=\"subtitle-noxiy\">\r\n            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/subtitle-1.png\" alt=\"No alt text\" \/>            <span>\r\n                Insurance Benefits            <\/span>\r\n        <\/div>\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d5f32c elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"5d5f32c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Health Care Security Through Insurance<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a8cc2a elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"1a8cc2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Health insurance policies can vary in their coverage options and costs, but they generally help individuals and families pay for medical expenses.\n\n<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f92ceef elementor-widget__width-initial elementor-widget elementor-widget-skill_bar_noxiy\" data-id=\"f92ceef\" data-element_type=\"widget\" data-widget_type=\"skill_bar_noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t                    <div class=\"skill__area-item\">\r\n                <div class=\"skill__area-item-content\">\r\n                    <h6>\r\n                        Life Protection                    <\/h6>\r\n                    <span class=\"skill__area-item-count text-two\"><span class=\"counter\">\r\n                            69                        <\/span>\r\n                        %                    <\/span>\r\n                <\/div>\r\n                <div class=\"skill__area-item-inner\">\r\n                    <div class=\"skill__area-item-bar\" data-width=\"69\"><\/div>\r\n                <\/div>\r\n            <\/div>\r\n                    <div class=\"skill__area-item\">\r\n                <div class=\"skill__area-item-content\">\r\n                    <h6>\r\n                        Customer Service                    <\/h6>\r\n                    <span class=\"skill__area-item-count text-two\"><span class=\"counter\">\r\n                            84                        <\/span>\r\n                        %                    <\/span>\r\n                <\/div>\r\n                <div class=\"skill__area-item-inner\">\r\n                    <div class=\"skill__area-item-bar\" data-width=\"84\"><\/div>\r\n                <\/div>\r\n            <\/div>\r\n        \r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-955350e elementor-widget elementor-widget-button-noxiy\" data-id=\"955350e\" data-element_type=\"widget\" data-widget_type=\"button-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"noxiy-button\">\r\n            <a href=\"\/about-us\" class=\"noxiy__btn\">\r\n                 Read More             <\/a>\r\n\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aca0bca elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aca0bca\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78d7a01\" data-id=\"78d7a01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45a045f elementor-widget elementor-widget-subtitle-noxiy\" data-id=\"45a045f\" data-element_type=\"widget\" data-widget_type=\"subtitle-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        <div class=\"subtitle-noxiy\">\r\n            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/subtitle-1.png\" alt=\"No alt text\" \/>            <span>\r\n                Digital Solution            <\/span>\r\n        <\/div>\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-349d248 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"349d248\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We Focus on Quality Care & Service.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f66bc7 elementor-widget elementor-widget-button-noxiy\" data-id=\"3f66bc7\" data-element_type=\"widget\" data-widget_type=\"button-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"noxiy-button\">\r\n            <a href=\"\/request-quote\" class=\"noxiy__btn\">\r\n                Request Quote            <\/a>\r\n\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2cf51d9\" data-id=\"2cf51d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22a5aea elementor-widget__width-initial elementor-widget elementor-widget-video-icon-noxiy\" data-id=\"22a5aea\" data-element_type=\"widget\" data-widget_type=\"video-icon-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"video-icon-aligment\">\r\n            <div class=\"solution__area-right-icon video video-pulse noxiy-video-icon\">\r\n                <a class=\"video-popup\" href=\"http:\/\/google.com\"><i\r\n                        class=\"fa fa-play\"><\/i><\/a>\r\n            <\/div>\r\n        <\/div>\r\n\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fa5eabd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fa5eabd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f57000b elementor-hidden-tablet\" data-id=\"f57000b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e7b814d\" data-id=\"e7b814d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6988a91 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"6988a91\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Watch The<br> Consulting Video<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b24c99f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b24c99f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23a6448\" data-id=\"23a6448\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-08be647 elementor-section-full_width elementor-section-content-bottom elementor-section-height-default elementor-section-height-default\" data-id=\"08be647\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bea5ebe\" data-id=\"bea5ebe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ceec06f elementor-widget elementor-widget-subtitle-noxiy\" data-id=\"ceec06f\" data-element_type=\"widget\" data-widget_type=\"subtitle-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\r\n        <div class=\"subtitle-noxiy\">\r\n            <img decoding=\"async\" src=\"https:\/\/finalnoxiy.themeori.com\/wp-content\/uploads\/2023\/07\/subtitle-1.png\" alt=\"No alt text\" \/>            <span>\r\n                From The Blog            <\/span>\r\n        <\/div>\r\n\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a0ac33 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9a0ac33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Blog & Articles<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-472564e\" data-id=\"472564e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9aaa7e8 elementor-widget elementor-widget-button-noxiy\" data-id=\"9aaa7e8\" data-element_type=\"widget\" data-widget_type=\"button-noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"noxiy-button\">\r\n            <a href=\"\/blog\" class=\"noxiy__btn\">\r\n                See more blog            <\/a>\r\n\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c80b5 elementor-widget elementor-widget-blog_grid_noxiy\" data-id=\"a6c80b5\" data-element_type=\"widget\" data-widget_type=\"blog_grid_noxiy.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n                    <div class=\"blog__four\">\r\n                <div class=\"container\">\r\n                    <div class=\"row\">\r\n                                                    <div class=\"col-xl-6 col-lg-6\">\r\n                                <div class=\"blog__four-item\">\r\n                                    <div class=\"blog__four-item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-content\/uploads\/2023\/07\/blog-1-1024x575.jpg\"\r\n                                            alt=\"\">\r\n                                        <div class=\"blog__four-item-image-date\">\r\n                                            <span>\r\n                                                August 23, 2023                                            <\/span>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                    <div class=\"blog__four-item-content\">\r\n                                        <ul>\r\n                                            <li><i class=\"fal fa-user-circle\"><\/i>\r\n                                                admin                                            <\/li>\r\n                                        <\/ul>\r\n                                        <h4><a href=\"#\">Blog Post<\/a><\/h4>\r\n                                        <p>\r\n                                            It is a long established fact that a reader will...                                        <\/p>\r\n                                        <a href=\"#\">Read More<i\r\n                                                class=\"far fa-long-arrow-right\"><\/i><\/a>\r\n                                    <\/div>\r\n\r\n                                <\/div>\r\n                            <\/div>\r\n                                                        <div class=\"col-xl-6 col-lg-6\">\r\n                                <div class=\"blog__four-item\">\r\n                                    <div class=\"blog__four-item-image\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-content\/uploads\/2023\/07\/Asia-Henley-2496x1404px-1024x576.webp\"\r\n                                            alt=\"\">\r\n                                        <div class=\"blog__four-item-image-date\">\r\n                                            <span>\r\n                                                August 23, 2023                                            <\/span>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                    <div class=\"blog__four-item-content\">\r\n                                        <ul>\r\n                                            <li><i class=\"fal fa-user-circle\"><\/i>\r\n                                                admin                                            <\/li>\r\n                                        <\/ul>\r\n                                        <h4><a href=\"#\">Blog Post<\/a><\/h4>\r\n                                        <p>\r\n                                            It is a long established fact that a reader will...                                        <\/p>\r\n                                        <a href=\"#\">Read More<i\r\n                                                class=\"far fa-long-arrow-right\"><\/i><\/a>\r\n                                    <\/div>\r\n\r\n                                <\/div>\r\n                            <\/div>\r\n                                                <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        \r\n\r\n        \r\n\r\n\r\n        \r\n\r\n        \r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Insurance Agency Invest in Your Health Our Seervices 500 + Customers Family Insurance Home Insurance Travel Insurance Disability Insurance Car Insurance Family Insurance Home Insurance Travel Insurance Disability Insurance Car Insurance 31 + Years Experience Our Company Company Overview Trusted Partner for Health Coverage Insurance brokers can help you find health coverage that meets your [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":1,"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":2422,"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/pages\/11\/revisions\/2422"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/DynamicDroneSolutions\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}