{"id":18,"date":"2023-07-14T00:12:29","date_gmt":"2023-07-14T00:12:29","guid":{"rendered":"https:\/\/themeholy.com\/wordpress\/rasm\/?page_id=18"},"modified":"2023-09-01T05:41:17","modified_gmt":"2023-09-01T05:41:17","slug":"about","status":"publish","type":"page","link":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/about\/","title":{"rendered":"About Us One"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18\" class=\"elementor elementor-18\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40cb8d0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"40cb8d0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2cc232\" data-id=\"d2cc232\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ebdbb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ebdbb4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-14647dc\" data-id=\"14647dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68063ad elementor-widget elementor-widget-rasmgroupimage\" data-id=\"68063ad\" data-element_type=\"widget\" data-widget_type=\"rasmgroupimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"img-box1\"><div class=\"img1\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/about_1.jpg\" alt=\"about_1\"  \/><\/div><div class=\"img2\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/about_2.jpg\" alt=\"about_2\"  \/><\/div><div class=\"img3\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/flower_1_3-1.png\" alt=\"flower_1_3 1\"  \/><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-745f4a7\" data-id=\"745f4a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-931c49a elementor-widget elementor-widget-rasmsectiontitle\" data-id=\"931c49a\" data-element_type=\"widget\" data-widget_type=\"rasmsectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-area mb-25\" ><span class=\"sub-title subtitle-selector\">About Us<img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/title_right.svg\" alt=\"title_right\"  class=\"icon\" \/><\/span><h2 class=\"sec-title title-selector\">Discover The Ultimate Spa Massage Experience<\/h2><p class=\"desc-selector\">Discover a world of tranquility, luxury, and personalized care as you embark\n                                on a journey of self-care and renewal. Visit us today and let us transport you to a realm of\n                                beauty and serenity.<\/p><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba075b elementor-widget elementor-widget-text-editor\" data-id=\"5ba075b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"about-wrapper\">\n<div class=\"about-info style2\">\n<h3 class=\"about-info_title h6\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/title_left.svg\" alt=\"\" \/>Personal Program<\/h3>\n<\/div>\n<div class=\"about-info style2\">\n<h3 class=\"about-info_title h6\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/title_left.svg\" alt=\"\" \/>Expert Nutritionist<\/h3>\n<\/div>\n<\/div>\nWe also offer private rooms for more intimate treatments and couples&#8217; packages for a romantic escape.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab48ff0 elementor-widget elementor-widget-rasmbutton\" data-id=\"ab48ff0\" data-element_type=\"widget\" data-widget_type=\"rasmbutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Button --><div class=\"btn-wrapper left\"><a class=\"th-btn\" href=\"https:\/\/themeholy.com\/wordpress\/rasm\/contact\/\">Discover More<i class=\"fa-regular fa-arrow-right ms-2\"><\/i><\/a><\/div><!-- End Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7754c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5a7754c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e93daa7\" data-id=\"e93daa7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb315d7 elementor-widget elementor-widget-rasmcounterup\" data-id=\"fb315d7\" data-element_type=\"widget\" data-widget_type=\"rasmcounterup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"overflow-hidden\"><div class=\"container\"><div class=\"counter-sec style4 space-top\"><div class=\"th-counterup wow fadeInLeft\"><div class=\"inner\"><div class=\"icon\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/counter_1_1.svg\" alt=\"counter_1_1\"  \/><\/div><div class=\"content\"><h3 class=\"counter\"><span class=\"odometer\" data-count=\"25\">00<\/span><span class=\"counter-number\">+<\/span><\/h3><p class=\"counter-card_text\">Years of Experience<\/p><\/div><\/div><\/div><div class=\"th-counterup wow fadeInLeft\"><div class=\"inner\"><div class=\"icon\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/counter_1_2.svg\" alt=\"counter_1_2\"  \/><\/div><div class=\"content\"><h3 class=\"counter\"><span class=\"odometer\" data-count=\"100\">00<\/span><span class=\"counter-number\">%<\/span><\/h3><p class=\"counter-card_text\">Natural Products<\/p><\/div><\/div><\/div><div class=\"th-counterup wow fadeInLeft\"><div class=\"inner\"><div class=\"icon\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/counter_1_3.svg\" alt=\"counter_1_3\"  \/><\/div><div class=\"content\"><h3 class=\"counter\"><span class=\"odometer\" data-count=\"56\">00<\/span><span class=\"counter-number\">k+<\/span><\/h3><p class=\"counter-card_text\">Satisfied Clients<\/p><\/div><\/div><\/div><div class=\"th-counterup wow fadeInLeft\"><div class=\"inner\"><div class=\"icon\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/counter_1_4.svg\" alt=\"counter_1_4\"  \/><\/div><div class=\"content\"><h3 class=\"counter\"><span class=\"odometer\" data-count=\"36\">00<\/span><span class=\"counter-number\">+<\/span><\/h3><p class=\"counter-card_text\">Specialists Team<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc50355 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cc50355\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8328d0f\" data-id=\"8328d0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0530e54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0530e54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-febcff6\" data-id=\"febcff6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-518e517 elementor-widget elementor-widget-rasmsectiontitle\" data-id=\"518e517\" data-element_type=\"widget\" data-widget_type=\"rasmsectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-area mb-25\" ><span class=\"sub-title subtitle-selector\">Why Choose Us<img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/title_right.svg\" alt=\"title_right\"  class=\"icon\" \/><\/span><h2 class=\"sec-title title-selector\">We Have 25 Years Of Experience With Nail Style.<\/h2><p class=\"desc-selector\">We prioritize the cleanrliness and comfort of our clients, ensuring a hygienic and relaxing environment throughout your visit. Our salon adheres to strict sanitization protocols, and all our tools.<\/p><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b8f3ed elementor-widget elementor-widget-rasmfeatures\" data-id=\"1b8f3ed\" data-element_type=\"widget\" data-widget_type=\"rasmfeatures.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"choose-about-wrap\"><div class=\"choose-about\"><div class=\"choose-about_icon\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/choose_1.svg\" alt=\"choose_1\"  \/><\/div><div class=\"media-body\"><h3 class=\"box-title\">\nBrand Nail Art Equipment<\/h3><p class=\"choose-about_text\">From classic manicures and pedicures to intricate nail art and personalized nail extensions<\/p><\/div><\/div><div class=\"choose-about\"><div class=\"choose-about_icon\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/choose_2.svg\" alt=\"choose_2\"  \/><\/div><div class=\"media-body\"><h3 class=\"box-title\">\nBest Place<\/h3><p class=\"choose-about_text\">That&#039;s why we only use premium quality nail polishes, gel, and other nail products from trusted brands.<\/p><\/div><\/div><div class=\"choose-about\"><div class=\"choose-about_icon\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/choose_3.svg\" alt=\"choose_3\"  \/><\/div><div class=\"media-body\"><h3 class=\"box-title\">\nSpecial Support<\/h3><p class=\"choose-about_text\">That&#039;s why we only use premium quality nail polishes, gel, and other nail products from trusted brands.<\/p><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07eb8a6\" data-id=\"07eb8a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8031033 elementor-widget elementor-widget-rasmgroupimage\" data-id=\"8031033\" data-element_type=\"widget\" data-widget_type=\"rasmgroupimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"choose-image\"><div class=\"img1  wow fadeInRight\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/choose_1.png\" alt=\"choose_1\"  \/><\/div><div class=\"img2 movingX\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/flower_1_3-2.png\" alt=\"flower_1_3 2\"  \/><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d7915e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2d7915e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8ce8f0\" data-id=\"f8ce8f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b7a8027 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7a8027\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4739b9b\" data-id=\"4739b9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e63cbec elementor-widget elementor-widget-rasmsectiontitle\" data-id=\"e63cbec\" data-element_type=\"widget\" data-widget_type=\"rasmsectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-area\" ><span class=\"sub-title subtitle-selector\">Make An Appointment<img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/title_right.svg\" alt=\"title_right\"  class=\"icon\" \/><\/span><h2 class=\"sec-title title-selector\">Experience the Magic of Our Nail Styling Services<\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fecb293 elementor-widget elementor-widget-text-editor\" data-id=\"fecb293\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"appointment-work  text-center text-lg-start\">\n                        <h4 class=\"work-title\">Working Hours:<\/h4>\n                        <p>we are dedicated to delivering exceptional results and ensuring your nails make a bold and\n                            beautiful statement.<\/p>\n                        <ul class=\"working-list\">\n                            <li>Monday to Friday<span>09:00am &#8211; 20:00pm<\/span><\/li>\n                            <li>Saturday<span>10:00am &#8211; 18:00pm<\/span><\/li>\n                            <li>Sunday<span>Closed<\/span><\/li>\n                        <\/ul>\n                    <\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b56466a\" data-id=\"b56466a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1010373 elementor-widget elementor-widget-shortcode\" data-id=\"1010373\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f710-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/Belladonna\/wp-json\/wp\/v2\/pages\/18#wpcf7-f710-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"710\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f710-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"appointment-quote-form\">\n    <div class=\"row\">\n        <div class=\"col-md-6 form-group\">\n            <i class=\"fa-sharp fa-light fa-user\"><\/i>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"text-941\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"text-941\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First Name\" value=\"\" type=\"text\" name=\"text-941\" \/><\/span>\n        <\/div>\n        <div class=\"col-md-6 form-group\">\n            <i class=\"fa-sharp fa-light fa-user\"><\/i>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"text-942\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"text-942\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Last Name\" value=\"\" type=\"text\" name=\"text-942\" \/><\/span>\n        <\/div>\n        <div class=\"col-md-6 form-group\">\n            <i class=\"fa-light fa-envelope-open\"><\/i>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"text-943\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"text-943\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email Address\" value=\"\" type=\"text\" name=\"text-943\" \/><\/span>\n        <\/div>\n        <div class=\"col-md-6 form-group\">\n            <i class=\"fa-light fa-phone\"><\/i>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"text-944\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"text-944\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"text\" name=\"text-944\" \/><\/span>\n        <\/div>\n        <div class=\"form-group col-12\">\n            <i class=\"fa-regular fa-tag\"><\/i>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"menu-248\"><select class=\"wpcf7-form-control wpcf7-select form-select nice-select\" id=\"menu-248\" aria-invalid=\"false\" name=\"menu-248\"><option value=\"Spa &amp; Massage\">Spa &amp; Massage<\/option><option value=\"Facial &amp; Massage\">Facial &amp; Massage<\/option><option value=\"Head Massage\">Head Massage<\/option><option value=\"Sports Massage\">Sports Massage<\/option><option value=\"Stone Massage\">Stone Massage<\/option><\/select><\/span>\n        <\/div>\n        <div class=\"form-group col-12\">\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"text-157\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text date-pick form-control\" id=\"text-157\" aria-invalid=\"false\" placeholder=\"Select Date\" value=\"\" type=\"text\" name=\"text-157\" \/><\/span>\n            <i class=\"fa-light fa-calendar-days\"><\/i>\n        <\/div>\n        <div class=\"form-group col-12\">\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"text-677\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text time-ptime-pick form-controlick form-control\" id=\"text-677\" aria-invalid=\"false\" placeholder=\"Select Time\" value=\"\" type=\"text\" name=\"text-677\" \/><\/span><i class=\"fa-light fa-clock\"><\/i>\n        <\/div>\n        <div class=\"btn-group justify-content-center justify-content-xl-start\">\n            <button class=\"th-btn style3 fw-btn wpcf7\">Make An Appointment<i class=\"fa-solid fa-arrow-right ms-2\"><\/i><\/button>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ab666b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ab666b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef8b057\" data-id=\"ef8b057\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87973ec elementor-widget elementor-widget-rasmcta\" data-id=\"87973ec\" data-element_type=\"widget\" data-widget_type=\"rasmcta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sec-shape\"><span class=\"sec-shape_img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/girl.svg\" alt=\"girl\"  \/><\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c4eddb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7c4eddb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1856b8\" data-id=\"c1856b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a47d47b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a47d47b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a2cdc17\" data-id=\"a2cdc17\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de4c962 elementor-widget elementor-widget-rasmsectiontitle\" data-id=\"de4c962\" data-element_type=\"widget\" data-widget_type=\"rasmsectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-area\" ><span class=\"sub-title subtitle-selector\">Expert Team<\/span><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/title_shape_1.svg\" alt=\"title_shape_1\"  class=\"icon\" \/><h2 class=\"sec-title title-selector\">Our Experience Specialists<\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f7722e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7722e6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-328b7ee\" data-id=\"328b7ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-715ae86 elementor-widget elementor-widget-rasmteam\" data-id=\"715ae86\" data-element_type=\"widget\" data-widget_type=\"rasmteam.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"row slider-shadow th-carousel teamSlide1\" id=\"teamSlide1\" data-slide-show=\"3\" data-lg-slide-show=\"3\" data-md-slide-show=\"2\" data-sm-slide-show=\"1\" data-xs-slide-show=\"1\"><!-- Single Item --><div class=\"col-sm-6 col-lg-4 col-xxl-3\"><div class=\"th-team team-card wow fadeInUp\"><div class=\"team-img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/team_1_1.jpg\" alt=\"team_1_1\"  \/><\/div><div class=\"team-card_content\"><div class=\"team-content\"><h3 class=\"box-title th-title \"><a  href=\"#\">Jenifer Lopez<\/a><\/h3><span class=\"team-desig\">Specialist<\/span><\/div><div class=\"team-social\"><div class=\"icon-btn\"><i class=\"fa-light fa-plus\"><\/i><\/div><div class=\"th-social\"><a  href=\"http:\/\/facebook.com\" class=\"icon-bg-custom\"><i class=\"fab fa-facebook-f\"><\/i><\/a><a  href=\"http:\/\/twitter.com\" class=\"icon-bg-custom\"><i class=\"fab fa-twitter\"><\/i><\/a><a  href=\"http:\/\/linkedin.com\" class=\"icon-bg-custom\"><i class=\"fab fa-linkedin-in\"><\/i><\/a><\/div><\/div><\/div> <\/div><\/div><!-- Single Item --><!-- Single Item --><div class=\"col-sm-6 col-lg-4 col-xxl-3\"><div class=\"th-team team-card wow fadeInUp\"><div class=\"team-img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/team_1_2.jpg\" alt=\"team_1_2\"  \/><\/div><div class=\"team-card_content\"><div class=\"team-content\"><h3 class=\"box-title th-title \"><a  href=\"#\">Arlene McCoy<\/a><\/h3><span class=\"team-desig\">Founder &amp; CEO<\/span><\/div><div class=\"team-social\"><div class=\"icon-btn\"><i class=\"fa-light fa-plus\"><\/i><\/div><div class=\"th-social\"><a  href=\"http:\/\/facebook.com\" class=\"icon-bg-custom\"><i class=\"fab fa-facebook-f\"><\/i><\/a><a  href=\"http:\/\/twitter.com\" class=\"icon-bg-custom\"><i class=\"fab fa-twitter\"><\/i><\/a><a  href=\"http:\/\/linkedin.com\" class=\"icon-bg-custom\"><i class=\"fab fa-linkedin-in\"><\/i><\/a><\/div><\/div><\/div> <\/div><\/div><!-- Single Item --><!-- Single Item --><div class=\"col-sm-6 col-lg-4 col-xxl-3\"><div class=\"th-team team-card wow fadeInUp\"><div class=\"team-img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/team_1_3.jpg\" alt=\"team_1_3\"  \/><\/div><div class=\"team-card_content\"><div class=\"team-content\"><h3 class=\"box-title th-title \"><a  href=\"#\">Robert Fox<\/a><\/h3><span class=\"team-desig\">Beautician<\/span><\/div><div class=\"team-social\"><div class=\"icon-btn\"><i class=\"fa-light fa-plus\"><\/i><\/div><div class=\"th-social\"><a  href=\"http:\/\/facebook.com\" class=\"icon-bg-custom\"><i class=\"fab fa-facebook-f\"><\/i><\/a><a  href=\"http:\/\/twitter.com\" class=\"icon-bg-custom\"><i class=\"fab fa-twitter\"><\/i><\/a><a  href=\"http:\/\/linkedin.com\" class=\"icon-bg-custom\"><i class=\"fab fa-linkedin-in\"><\/i><\/a><\/div><\/div><\/div> <\/div><\/div><!-- Single Item --><!-- Single Item --><div class=\"col-sm-6 col-lg-4 col-xxl-3\"><div class=\"th-team team-card wow fadeInUp\"><div class=\"team-img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/team_1_1.jpg\" alt=\"team_1_1\"  \/><\/div><div class=\"team-card_content\"><div class=\"team-content\"><h3 class=\"box-title th-title \"><a  href=\"#\">Jenifer Lopez<\/a><\/h3><span class=\"team-desig\">Specialist<\/span><\/div><div class=\"team-social\"><div class=\"icon-btn\"><i class=\"fa-light fa-plus\"><\/i><\/div><div class=\"th-social\"><a  href=\"http:\/\/facebook.com\" class=\"icon-bg-custom\"><i class=\"fab fa-facebook-f\"><\/i><\/a><a  href=\"http:\/\/twitter.com\" class=\"icon-bg-custom\"><i class=\"fab fa-twitter\"><\/i><\/a><a  href=\"http:\/\/linkedin.com\" class=\"icon-bg-custom\"><i class=\"fab fa-linkedin-in\"><\/i><\/a><\/div><\/div><\/div> <\/div><\/div><!-- Single Item --><!-- Single Item --><div class=\"col-sm-6 col-lg-4 col-xxl-3\"><div class=\"th-team team-card wow fadeInUp\"><div class=\"team-img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/team_1_2.jpg\" alt=\"team_1_2\"  \/><\/div><div class=\"team-card_content\"><div class=\"team-content\"><h3 class=\"box-title th-title \"><a  href=\"#\">Arlene McCoy<\/a><\/h3><span class=\"team-desig\">Founder &amp; CEO<\/span><\/div><div class=\"team-social\"><div class=\"icon-btn\"><i class=\"fa-light fa-plus\"><\/i><\/div><div class=\"th-social\"><a  href=\"http:\/\/facebook.com\" class=\"icon-bg-custom\"><i class=\"fab fa-facebook-f\"><\/i><\/a><a  href=\"http:\/\/twitter.com\" class=\"icon-bg-custom\"><i class=\"fab fa-twitter\"><\/i><\/a><a  href=\"http:\/\/linkedin.com\" class=\"icon-bg-custom\"><i class=\"fab fa-linkedin-in\"><\/i><\/a><\/div><\/div><\/div> <\/div><\/div><!-- Single Item --><!-- Single Item --><div class=\"col-sm-6 col-lg-4 col-xxl-3\"><div class=\"th-team team-card wow fadeInUp\"><div class=\"team-img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/team_1_3.jpg\" alt=\"team_1_3\"  \/><\/div><div class=\"team-card_content\"><div class=\"team-content\"><h3 class=\"box-title th-title \"><a  href=\"#\">Robert Fox<\/a><\/h3><span class=\"team-desig\">Beautician<\/span><\/div><div class=\"team-social\"><div class=\"icon-btn\"><i class=\"fa-light fa-plus\"><\/i><\/div><div class=\"th-social\"><a  href=\"http:\/\/facebook.com\" class=\"icon-bg-custom\"><i class=\"fab fa-facebook-f\"><\/i><\/a><a  href=\"http:\/\/twitter.com\" class=\"icon-bg-custom\"><i class=\"fab fa-twitter\"><\/i><\/a><a  href=\"http:\/\/linkedin.com\" class=\"icon-bg-custom\"><i class=\"fab fa-linkedin-in\"><\/i><\/a><\/div><\/div><\/div> <\/div><\/div><!-- Single Item --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffd1cff elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ffd1cff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca5abb4\" data-id=\"ca5abb4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"shape-mockup-area elementor-element elementor-element-aa86b30 elementor-widget elementor-widget-rasmshapeimage\" data-id=\"aa86b30\" data-element_type=\"widget\" data-widget_type=\"rasmshapeimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Image --><div class=\"shape-mockup  d-lg-block d-none Classical\" data-top=\"1.0E-5px\" data-left=\"0.0001px\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/flower_1_1.png\" alt=\"Belladonna\" ><\/div><!-- End Image -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3840d1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3840d1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ccad24e\" data-id=\"ccad24e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31c7771 elementor-widget elementor-widget-rasmsectiontitle\" data-id=\"31c7771\" data-element_type=\"widget\" data-widget_type=\"rasmsectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-area\" ><span class=\"sub-title subtitle-selector\">Testimonials<\/span><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/title_shape_1.svg\" alt=\"title_shape_1\"  class=\"icon\" \/><h2 class=\"sec-title title-selector\">Our Customer Feedback<\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d517951 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d517951\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-369dab7\" data-id=\"369dab7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3979fe elementor-widget elementor-widget-rasmtestimonialslider\" data-id=\"f3979fe\" data-element_type=\"widget\" data-widget_type=\"rasmtestimonialslider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"row slider-shadow th-carousel\" data-slide-show=\"3\" data-lg-slide-show=\"2\" data-sm-slide-show=\"1\" data-xs-slide-show=\"1\"><div class=\"col-md-6 col-lg-4\"><div class=\"testi-grid\"><div class=\"testi-grid_img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/testi_2_1.png\" alt=\"testi_2_1\"  \/><\/div><h3 class=\"box-title th-text\">Whether youre preparing for a special occasion or simply want to pamper yourself our talented stylists will work closely with you to create.<\/h3><div class=\"testi-grid_profile\"><div class=\"media-body\"><h5 class=\"testi-grid_name th-name\">Angelina Margret<\/h5><p class=\"testi-grid_desig th-desig\">Customer<\/p><\/div><\/div><div class=\"testi-quote\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/quote_2.png\" alt=\"quote_2\"  \/><\/div><div class=\"testi-shape1\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/leaf_2.svg\" alt=\"leaf_2\"  \/><\/div><div class=\"testi-shape2\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/flower_1_6.svg\" alt=\"flower_1_6\"  \/><\/div><\/div><\/div><div class=\"col-md-6 col-lg-4\"><div class=\"testi-grid\"><div class=\"testi-grid_img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/testi_2_2.png\" alt=\"testi_2_2\"  \/><\/div><h3 class=\"box-title th-text\">Parallel task user friendly through supply are chains. Dynamically simplify reliable meta service visionary sources unleash tactical.<\/h3><div class=\"testi-grid_profile\"><div class=\"media-body\"><h5 class=\"testi-grid_name th-name\">Senjuti das<\/h5><p class=\"testi-grid_desig th-desig\">Customer<\/p><\/div><\/div><div class=\"testi-quote\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/quote_2.png\" alt=\"quote_2\"  \/><\/div><div class=\"testi-shape1\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/leaf_2.svg\" alt=\"leaf_2\"  \/><\/div><div class=\"testi-shape2\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/flower_1_6.svg\" alt=\"flower_1_6\"  \/><\/div><\/div><\/div><div class=\"col-md-6 col-lg-4\"><div class=\"testi-grid\"><div class=\"testi-grid_img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/testi_2_3.png\" alt=\"testi_2_3\"  \/><\/div><h3 class=\"box-title th-text\">Continually utilize 24\/365 bandwidth before real-time interfaces. Proin mollis, ipsum vel ultrices dictum. Credibly grow users deliver.<\/h3><div class=\"testi-grid_profile\"><div class=\"media-body\"><h5 class=\"testi-grid_name th-name\">Jenifer Lopez<\/h5><p class=\"testi-grid_desig th-desig\">Customer<\/p><\/div><\/div><div class=\"testi-quote\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/quote_2.png\" alt=\"quote_2\"  \/><\/div><div class=\"testi-shape1\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/leaf_2.svg\" alt=\"leaf_2\"  \/><\/div><div class=\"testi-shape2\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/flower_1_6.svg\" alt=\"flower_1_6\"  \/><\/div><\/div><\/div><div class=\"col-md-6 col-lg-4\"><div class=\"testi-grid\"><div class=\"testi-grid_img\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/testi_2_3.png\" alt=\"testi_2_3\"  \/><\/div><h3 class=\"box-title th-text\">Intrinsicly pontifice pandemic ships growth strategies and partner convergence lives multidi sciplinar business Proin mollis ultrices<\/h3><div class=\"testi-grid_profile\"><div class=\"media-body\"><h5 class=\"testi-grid_name th-name\">Dianne Russell<\/h5><p class=\"testi-grid_desig th-desig\">Customer<\/p><\/div><\/div><div class=\"testi-quote\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/quote_2.png\" alt=\"quote_2\"  \/><\/div><div class=\"testi-shape1\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/leaf_2.svg\" alt=\"leaf_2\"  \/><\/div><div class=\"testi-shape2\"><img decoding=\"async\" src=\"https:\/\/themeholy.com\/wordpress\/rasm\/wp-content\/uploads\/2023\/07\/flower_1_6.svg\" alt=\"flower_1_6\"  \/><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>About Us Discover The Ultimate Spa Massage Experience Discover a world of tranquility, luxury, and personalized care as you embark on a journey of self-care and renewal. Visit us today and let us transport you to a realm of beauty and serenity. Personal Program Expert Nutritionist We also offer private rooms for more intimate treatments&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-builder.php","meta":{"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":1,"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":2098,"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/pages\/18\/revisions\/2098"}],"wp:attachment":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Belladonna\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}