{"id":9,"count":1,"description":"","link":"https:\/\/testv45.demowebsitelinks.com\/Ag-Strategies\/category\/soil-and-water\/","name":"Soil and Water","slug":"soil-and-water","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Ag-Strategies\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Ag-Strategies\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Ag-Strategies\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/testv45.demowebsitelinks.com\/Ag-Strategies\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}